{"id":32,"date":"2018-07-24T18:58:38","date_gmt":"2018-07-24T21:58:38","guid":{"rendered":"http:\/\/maurofelippe.com.br\/?page_id=32"},"modified":"2023-08-08T14:21:46","modified_gmt":"2023-08-08T17:21:46","slug":"imprensa","status":"publish","type":"page","link":"https:\/\/maurofelippe.com\/br\/imprensa\/","title":{"rendered":"Na imprensa"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"32\" class=\"elementor elementor-32\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd85d4f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd85d4f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c44af7\" data-id=\"7c44af7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-03abdba elementor-widget elementor-widget-heading\" data-id=\"03abdba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Leia o que saiu na imprensa sobre o Mauro Felippe<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-041b733 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"041b733\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd53153\" data-id=\"bd53153\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-423f4af elementor-widget elementor-widget-shortcode\" data-id=\"423f4af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"ct-posts-shortcode\" data-prefix=\"blog\"><div class=\"entries\" data-archive=\"default\" data-layout=\"grid\" data-cards=\"boxed\"><article class=\"entry-card card-content post-2087 post type-post status-publish format-standard has-post-thumbnail hentry category-imprensa category-materias-publicadas tag-bienal tag-bienaldolivrorio2023 tag-catarse tag-lc tag-literatura tag-livro tag-livros tag-mauro-felippe tag-obras tag-poesia tag-poeta\" ><a class=\"ct-media-container boundless-image\" href=\"https:\/\/maurofelippe.com\/br\/entrevista-de-mauro-felippe-a-lc-o-caos-da-existencia-humana-em-forma-de-poesia\/\" aria-label=\"Entrevista de Mauro Felippe a LC:  O caos da exist\u00eancia humana em forma de poesia\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/10\/lc-logo.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/10\/lc-logo.jpg 500w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/10\/lc-logo-300x300.jpg 300w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/10\/lc-logo-150x150.jpg 150w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/10\/lc-logo-12x12.jpg 12w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" itemprop=\"image\" style=\"aspect-ratio: 4\/3;\" \/><\/a><h2 class=\"entry-title\"><a href=\"https:\/\/maurofelippe.com\/br\/entrevista-de-mauro-felippe-a-lc-o-caos-da-existencia-humana-em-forma-de-poesia\/\" rel=\"bookmark\">Entrevista de Mauro Felippe a LC:  O caos da exist\u00eancia humana em forma de poesia<\/a><\/h2><ul class=\"entry-meta\" data-type=\"simple:slash\" data-id=\"tGBemD\" ><li class=\"meta-categories\" data-type=\"simple\"><a href=\"https:\/\/maurofelippe.com\/br\/category\/imprensa\/\" rel=\"tag\" class=\"ct-term-4\">Imprensa<\/a>, <a href=\"https:\/\/maurofelippe.com\/br\/category\/materias-publicadas\/\" rel=\"tag\" class=\"ct-term-176\">Mat\u00e9rias publicadas<\/a><\/li><\/ul><div class=\"entry-excerpt\"><p>Marcadas por uma escrita intensa e por vezes fren\u00e9tica, as palavras de\u00a0Mauro Felippe\u00a0t\u00eam a capacidade de libertar e expressar o \u00e2mago\u2026<\/p>\n<\/div><a class=\"entry-button wp-element-button ct-button\" href=\"https:\/\/maurofelippe.com\/br\/entrevista-de-mauro-felippe-a-lc-o-caos-da-existencia-humana-em-forma-de-poesia\/\">Leia mais<span class=\"screen-reader-text\">Entrevista de Mauro Felippe a LC:  O caos da exist\u00eancia humana em forma de poesia<\/span><\/a><\/article><article class=\"entry-card card-content post-2072 post type-post status-publish format-standard has-post-thumbnail hentry category-imprensa category-materias-publicadas tag-bienadolivro2023 tag-catarse tag-livro tag-livros tag-mauro-felippe tag-obras tag-poesia tag-poeta\" ><a class=\"ct-media-container boundless-image\" href=\"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-coluna-do-nei-lopes-nd\/\" aria-label=\"Mauro Felippe na coluna do Nei Lopes | ND+\"><img loading=\"lazy\" decoding=\"async\" width=\"333\" height=\"333\" src=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/mauro-neythumb.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/mauro-neythumb.jpg 333w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/mauro-neythumb-300x300.jpg 300w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/mauro-neythumb-150x150.jpg 150w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/mauro-neythumb-12x12.jpg 12w\" sizes=\"auto, (max-width: 333px) 100vw, 333px\" itemprop=\"image\" style=\"aspect-ratio: 4\/3;\" \/><\/a><h2 class=\"entry-title\"><a href=\"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-coluna-do-nei-lopes-nd\/\" rel=\"bookmark\">Mauro Felippe na coluna do Nei Lopes | ND+<\/a><\/h2><ul class=\"entry-meta\" data-type=\"simple:slash\" data-id=\"tGBemD\" ><li class=\"meta-categories\" data-type=\"simple\"><a href=\"https:\/\/maurofelippe.com\/br\/category\/imprensa\/\" rel=\"tag\" class=\"ct-term-4\">Imprensa<\/a>, <a href=\"https:\/\/maurofelippe.com\/br\/category\/materias-publicadas\/\" rel=\"tag\" class=\"ct-term-176\">Mat\u00e9rias publicadas<\/a><\/li><\/ul><div class=\"entry-excerpt\"><p>&nbsp;Livros e livrarias aqui:&nbsp; Contato com o autor e redes sociais: Facebook:&nbsp; Instagram:&nbsp;www.Instagram.com\/maurofelippe Youtube:&nbsp;www.Youtube.com\/maurofelippe Linktree:&nbsp;<\/p>\n<\/div><a class=\"entry-button wp-element-button ct-button\" href=\"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-coluna-do-nei-lopes-nd\/\">Leia mais<span class=\"screen-reader-text\">Mauro Felippe na coluna do Nei Lopes | ND+<\/span><\/a><\/article><article class=\"entry-card card-content post-2060 post type-post status-publish format-standard has-post-thumbnail hentry category-imprensa category-materias-publicadas tag-bienaldolivrorio2023 tag-catarse tag-literatura tag-livro tag-livros tag-mauro-felippe tag-obras tag-poesia tag-poeta\" ><a class=\"ct-media-container boundless-image\" href=\"https:\/\/maurofelippe.com\/br\/catarse-na-coluna-do-eraldo-luiz-da-silva\/\" aria-label=\"Catarse na coluna do eraldo luiz da silva\"><img loading=\"lazy\" decoding=\"async\" width=\"561\" height=\"542\" src=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-10.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-10.png 561w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-10-300x290.png 300w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-10-12x12.png 12w\" sizes=\"auto, (max-width: 561px) 100vw, 561px\" itemprop=\"image\" style=\"aspect-ratio: 4\/3;\" \/><\/a><h2 class=\"entry-title\"><a href=\"https:\/\/maurofelippe.com\/br\/catarse-na-coluna-do-eraldo-luiz-da-silva\/\" rel=\"bookmark\">Catarse na coluna do eraldo luiz da silva<\/a><\/h2><ul class=\"entry-meta\" data-type=\"simple:slash\" data-id=\"tGBemD\" ><li class=\"meta-categories\" data-type=\"simple\"><a href=\"https:\/\/maurofelippe.com\/br\/category\/imprensa\/\" rel=\"tag\" class=\"ct-term-4\">Imprensa<\/a>, <a href=\"https:\/\/maurofelippe.com\/br\/category\/materias-publicadas\/\" rel=\"tag\" class=\"ct-term-176\">Mat\u00e9rias publicadas<\/a><\/li><\/ul><div class=\"entry-excerpt\"><p>&nbsp;Livros e livrarias aqui:&nbsp; Contato com o autor e redes sociais: Facebook:&nbsp; Instagram:&nbsp;www.Instagram.com\/maurofelippe Youtube:&nbsp;www.Youtube.com\/maurofelippe Linktree:&nbsp;<\/p>\n<\/div><a class=\"entry-button wp-element-button ct-button\" href=\"https:\/\/maurofelippe.com\/br\/catarse-na-coluna-do-eraldo-luiz-da-silva\/\">Leia mais<span class=\"screen-reader-text\">Catarse na coluna do eraldo luiz da silva<\/span><\/a><\/article><article class=\"entry-card card-content post-2056 post type-post status-publish format-standard has-post-thumbnail hentry category-imprensa category-materias-publicadas tag-bienadolivro2023 tag-bienaldolivrorio2023 tag-catarse tag-literatura tag-livro tag-mauro-felippe tag-obras tag-poesia tag-poeta\" ><a class=\"ct-media-container boundless-image\" href=\"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-diario-carioca\/\" aria-label=\"Mauro Felippe no Diario Carioca\"><img loading=\"lazy\" decoding=\"async\" width=\"763\" height=\"763\" src=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-9.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-9.png 763w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-9-300x300.png 300w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-9-150x150.png 150w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-9-12x12.png 12w\" sizes=\"auto, (max-width: 763px) 100vw, 763px\" itemprop=\"image\" style=\"aspect-ratio: 4\/3;\" \/><\/a><h2 class=\"entry-title\"><a href=\"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-diario-carioca\/\" rel=\"bookmark\">Mauro Felippe no Diario Carioca<\/a><\/h2><ul class=\"entry-meta\" data-type=\"simple:slash\" data-id=\"tGBemD\" ><li class=\"meta-categories\" data-type=\"simple\"><a href=\"https:\/\/maurofelippe.com\/br\/category\/imprensa\/\" rel=\"tag\" class=\"ct-term-4\">Imprensa<\/a>, <a href=\"https:\/\/maurofelippe.com\/br\/category\/materias-publicadas\/\" rel=\"tag\" class=\"ct-term-176\">Mat\u00e9rias publicadas<\/a><\/li><\/ul><div class=\"entry-excerpt\"><p>&nbsp;Livros e livrarias aqui:&nbsp; Contato com o autor e redes sociais: Facebook:&nbsp; Instagram:&nbsp;www.Instagram.com\/maurofelippe Youtube:&nbsp;www.Youtube.com\/maurofelippe Linktree:&nbsp;<\/p>\n<\/div><a class=\"entry-button wp-element-button ct-button\" href=\"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-diario-carioca\/\">Leia mais<span class=\"screen-reader-text\">Mauro Felippe no Diario Carioca<\/span><\/a><\/article><article class=\"entry-card card-content post-2050 post type-post status-publish format-standard has-post-thumbnail hentry category-imprensa category-materias-publicadas tag-bienadolivro2023 tag-catarse tag-literatura tag-livro tag-mauro-felippe tag-obras tag-poesia tag-poeta\" ><a class=\"ct-media-container boundless-image\" href=\"https:\/\/maurofelippe.com\/br\/2050-2\/\" aria-label=\"CATARSE, no Blog &#8216;Acontece&#8217;\"><img loading=\"lazy\" decoding=\"async\" width=\"279\" height=\"253\" src=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-7.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-7.png 279w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-7-13x12.png 13w\" sizes=\"auto, (max-width: 279px) 100vw, 279px\" itemprop=\"image\" style=\"aspect-ratio: 4\/3;\" \/><\/a><h2 class=\"entry-title\"><a href=\"https:\/\/maurofelippe.com\/br\/2050-2\/\" rel=\"bookmark\">CATARSE, no Blog &#8216;Acontece&#8217;<\/a><\/h2><ul class=\"entry-meta\" data-type=\"simple:slash\" data-id=\"tGBemD\" ><li class=\"meta-categories\" data-type=\"simple\"><a href=\"https:\/\/maurofelippe.com\/br\/category\/imprensa\/\" rel=\"tag\" class=\"ct-term-4\">Imprensa<\/a>, <a href=\"https:\/\/maurofelippe.com\/br\/category\/materias-publicadas\/\" rel=\"tag\" class=\"ct-term-176\">Mat\u00e9rias publicadas<\/a><\/li><\/ul><div class=\"entry-excerpt\"><p>CATARSE, no Blog &#8216;Acontece&#8217;, do Esp\u00edrito Santo &#8211; ES. Entrevista completa j\u00e1 postada no meu Site, demais redes, e no pr\u00f3prio\u2026<\/p>\n<\/div><a class=\"entry-button wp-element-button ct-button\" href=\"https:\/\/maurofelippe.com\/br\/2050-2\/\">Leia mais<span class=\"screen-reader-text\">CATARSE, no Blog &#8216;Acontece&#8217;<\/span><\/a><\/article><article class=\"entry-card card-content post-2046 post type-post status-publish format-standard has-post-thumbnail hentry category-imprensa category-materias-publicadas tag-bienadolivro2023 tag-catarse tag-literatura tag-mauro-felippe tag-obras tag-poesia tag-poeta\" ><a class=\"ct-media-container boundless-image\" href=\"https:\/\/maurofelippe.com\/br\/catarse-no-portal-meia-92\/\" aria-label=\"CATARSE, no Portal Meia 92\"><img loading=\"lazy\" decoding=\"async\" width=\"497\" height=\"488\" src=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-6.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-6.png 497w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-6-300x295.png 300w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-6-12x12.png 12w\" sizes=\"auto, (max-width: 497px) 100vw, 497px\" itemprop=\"image\" style=\"aspect-ratio: 4\/3;\" \/><\/a><h2 class=\"entry-title\"><a href=\"https:\/\/maurofelippe.com\/br\/catarse-no-portal-meia-92\/\" rel=\"bookmark\">CATARSE, no Portal Meia 92<\/a><\/h2><ul class=\"entry-meta\" data-type=\"simple:slash\" data-id=\"tGBemD\" ><li class=\"meta-categories\" data-type=\"simple\"><a href=\"https:\/\/maurofelippe.com\/br\/category\/imprensa\/\" rel=\"tag\" class=\"ct-term-4\">Imprensa<\/a>, <a href=\"https:\/\/maurofelippe.com\/br\/category\/materias-publicadas\/\" rel=\"tag\" class=\"ct-term-176\">Mat\u00e9rias publicadas<\/a><\/li><\/ul><div class=\"entry-excerpt\"><p>CATARSE, no @portalmeia92, de S\u00e3o Paulo-SP. Belo portal de entretenimento. Entrevista completa no pr\u00f3prio Portal, que desde j\u00e1 o agrade\u00e7o! Acesse\u2026<\/p>\n<\/div><a class=\"entry-button wp-element-button ct-button\" href=\"https:\/\/maurofelippe.com\/br\/catarse-no-portal-meia-92\/\">Leia mais<span class=\"screen-reader-text\">CATARSE, no Portal Meia 92<\/span><\/a><\/article><article class=\"entry-card card-content post-2041 post type-post status-publish format-standard has-post-thumbnail hentry category-imprensa category-materias-publicadas tag-bienal tag-bienaldolivrorio2023 tag-catarse tag-imirante tag-literatura tag-livro tag-lura tag-mauro-felippe tag-obras tag-poesia tag-poeta\" ><a class=\"ct-media-container boundless-image\" href=\"https:\/\/maurofelippe.com\/br\/catarse-no-site-do-imirante-com\/\" aria-label=\"CATARSE, no Site do Imirante.com\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"403\" src=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-4-768x403.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-4-768x403.png 768w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-4-300x158.png 300w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-4-1024x538.png 1024w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-4-18x9.png 18w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-4.png 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" itemprop=\"image\" style=\"aspect-ratio: 4\/3;\" \/><\/a><h2 class=\"entry-title\"><a href=\"https:\/\/maurofelippe.com\/br\/catarse-no-site-do-imirante-com\/\" rel=\"bookmark\">CATARSE, no Site do Imirante.com<\/a><\/h2><ul class=\"entry-meta\" data-type=\"simple:slash\" data-id=\"tGBemD\" ><li class=\"meta-categories\" data-type=\"simple\"><a href=\"https:\/\/maurofelippe.com\/br\/category\/imprensa\/\" rel=\"tag\" class=\"ct-term-4\">Imprensa<\/a>, <a href=\"https:\/\/maurofelippe.com\/br\/category\/materias-publicadas\/\" rel=\"tag\" class=\"ct-term-176\">Mat\u00e9rias publicadas<\/a><\/li><\/ul><div class=\"entry-excerpt\"><p>CATARSE, no Site do Imirante.com, do Grupo Mirante, o maior de comunica\u00e7\u00f5es do Maranh\u00e3o. Mat\u00e9ria completa j\u00e1 postada no meu Site\u2026<\/p>\n<\/div><a class=\"entry-button wp-element-button ct-button\" href=\"https:\/\/maurofelippe.com\/br\/catarse-no-site-do-imirante-com\/\">Leia mais<span class=\"screen-reader-text\">CATARSE, no Site do Imirante.com<\/span><\/a><\/article><article class=\"entry-card card-content post-2027 post type-post status-publish format-standard has-post-thumbnail hentry category-materias-publicadas tag-bienaldolivro tag-catarse tag-divulgacao tag-espiritosantonoticias tag-lancamento tag-literatura tag-livro tag-livros tag-luraeditorial tag-mauro-felippe tag-poesia tag-poeta\" ><a class=\"ct-media-container boundless-image\" href=\"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-espirito-santo-noticias\/\" aria-label=\"MAURO FELIPPE NO Esp\u00edrito Santo Not\u00edcias&#8217;\"><img loading=\"lazy\" decoding=\"async\" width=\"310\" height=\"328\" src=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/image-9.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/image-9.png 310w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/image-9-284x300.png 284w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/image-9-11x12.png 11w\" sizes=\"auto, (max-width: 310px) 100vw, 310px\" itemprop=\"image\" style=\"aspect-ratio: 4\/3;\" \/><\/a><h2 class=\"entry-title\"><a href=\"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-espirito-santo-noticias\/\" rel=\"bookmark\">MAURO FELIPPE NO Esp\u00edrito Santo Not\u00edcias&#8217;<\/a><\/h2><ul class=\"entry-meta\" data-type=\"simple:slash\" data-id=\"tGBemD\" ><li class=\"meta-categories\" data-type=\"simple\"><a href=\"https:\/\/maurofelippe.com\/br\/category\/materias-publicadas\/\" rel=\"tag\" class=\"ct-term-176\">Mat\u00e9rias publicadas<\/a><\/li><\/ul><div class=\"entry-excerpt\"><p>Nova mat\u00e9ria sobre o meu novo livro CATARSE, pela Lura Editorial. Obrigado, &#8216;Esp\u00edrito Santo Not\u00edcias&#8217;, pelo release no Portal\/Jornal, via Sudeste\u2026<\/p>\n<\/div><a class=\"entry-button wp-element-button ct-button\" href=\"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-espirito-santo-noticias\/\">Leia mais<span class=\"screen-reader-text\">MAURO FELIPPE NO Esp\u00edrito Santo Not\u00edcias&#8217;<\/span><\/a><\/article><article class=\"entry-card card-content post-1999 post type-post status-publish format-standard has-post-thumbnail hentry category-materias-publicadas tag-catarse tag-divulgacao tag-lc tag-leiamais tag-literaturanacional tag-livro tag-livros tag-livrosrecomendados tag-luraeditorial tag-maurofelippe tag-obras tag-poesia tag-poesiailustrada tag-poeta tag-revistacaras tag-uol\" ><a class=\"ct-media-container boundless-image\" href=\"https:\/\/maurofelippe.com\/br\/catarse-na-revista-caras\/\" aria-label=\"Catarse na &#8216;Revista Caras&#8217;\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/channels4_profile-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/channels4_profile-768x768.jpg 768w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/channels4_profile-300x300.jpg 300w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/channels4_profile-150x150.jpg 150w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/channels4_profile-12x12.jpg 12w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/channels4_profile.jpg 900w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" itemprop=\"image\" style=\"aspect-ratio: 4\/3;\" \/><\/a><h2 class=\"entry-title\"><a href=\"https:\/\/maurofelippe.com\/br\/catarse-na-revista-caras\/\" rel=\"bookmark\">Catarse na &#8216;Revista Caras&#8217;<\/a><\/h2><ul class=\"entry-meta\" data-type=\"simple:slash\" data-id=\"tGBemD\" ><li class=\"meta-categories\" data-type=\"simple\"><a href=\"https:\/\/maurofelippe.com\/br\/category\/materias-publicadas\/\" rel=\"tag\" class=\"ct-term-176\">Mat\u00e9rias publicadas<\/a><\/li><\/ul><div class=\"entry-excerpt\"><p>Na m\u00eddia, por Lura Editorial: &#8220;Grandes Not\u00edcias! Estamos entusiasmados em compartilhar com voc\u00eas que o nosso livro &#8220;Catarse&#8221;, escrito pelo incr\u00edvel\u2026<\/p>\n<\/div><a class=\"entry-button wp-element-button ct-button\" href=\"https:\/\/maurofelippe.com\/br\/catarse-na-revista-caras\/\">Leia mais<span class=\"screen-reader-text\">Catarse na &#8216;Revista Caras&#8217;<\/span><\/a><\/article><\/div>\n\t\t<nav class=\"ct-pagination\" data-pagination=\"simple\"  >\n\t\t\t<div class=\"ct-hidden-sm\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/pages\/32\/page\/2\/\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/pages\/32\/page\/3\/\">3<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/pages\/32\/page\/4\/\">4<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/pages\/32\/page\/16\/\">16<\/a><\/div><a class=\"next page-numbers\" rel=\"next\" href=\"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/pages\/32\/page\/2\/\">Pr\u00f3xima <svg width=\"9px\" height=\"9px\" viewBox=\"0 0 15 15\" fill=\"currentColor\"><path d=\"M4.1,15c0.2,0,0.4-0.1,0.6-0.2L11.4,8c0.3-0.3,0.3-0.8,0-1.1L4.8,0.2C4.5-0.1,4-0.1,3.7,0.2C3.4,0.5,3.4,1,3.7,1.3l6.1,6.1l-6.2,6.2c-0.3,0.3-0.3,0.8,0,1.1C3.7,14.9,3.9,15,4.1,15z\"\/><\/svg><\/a>\n\t\t\t\n\t\t<\/nav><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Leia o que saiu na imprensa sobre o Mauro Felippe<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-32","page","type-page","status-publish","hentry"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Na imprensa - Mauro Felippe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maurofelippe.com\/br\/imprensa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Na imprensa - Mauro Felippe\" \/>\n<meta property=\"og:description\" content=\"Leia o que saiu na imprensa sobre o Mauro Felippe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maurofelippe.com\/br\/imprensa\/\" \/>\n<meta property=\"og:site_name\" content=\"Mauro Felippe\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-08T17:21:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/br\\\/imprensa\\\/\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/br\\\/imprensa\\\/\",\"name\":\"Na imprensa - Mauro Felippe\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\"},\"datePublished\":\"2018-07-24T21:58:38+00:00\",\"dateModified\":\"2023-08-08T17:21:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/br\\\/imprensa\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maurofelippe.com\\\/br\\\/imprensa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/br\\\/imprensa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maurofelippe.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Na imprensa\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\",\"url\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/\",\"name\":\"Mauro Felippe\",\"description\":\"Autor e Escritor\",\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\",\"name\":\"Mauro Felippe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"width\":164,\"height\":86,\"caption\":\"Mauro Felippe\"},\"logo\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\"},\"sameAs\":[\"http:\\\/\\\/www.maurofelippe.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Na imprensa - Mauro Felippe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maurofelippe.com\/br\/imprensa\/","og_locale":"pt_BR","og_type":"article","og_title":"Na imprensa - Mauro Felippe","og_description":"Leia o que saiu na imprensa sobre o Mauro Felippe","og_url":"https:\/\/maurofelippe.com\/br\/imprensa\/","og_site_name":"Mauro Felippe","article_modified_time":"2023-08-08T17:21:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/maurofelippe.com\/br\/imprensa\/","url":"https:\/\/maurofelippe.com\/br\/imprensa\/","name":"Na imprensa - Mauro Felippe","isPartOf":{"@id":"http:\/\/maurofelippe.com\/br\/#website"},"datePublished":"2018-07-24T21:58:38+00:00","dateModified":"2023-08-08T17:21:46+00:00","breadcrumb":{"@id":"https:\/\/maurofelippe.com\/br\/imprensa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maurofelippe.com\/br\/imprensa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maurofelippe.com\/br\/imprensa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maurofelippe.com\/"},{"@type":"ListItem","position":2,"name":"Na imprensa"}]},{"@type":"WebSite","@id":"http:\/\/maurofelippe.com\/br\/#website","url":"http:\/\/maurofelippe.com\/br\/","name":"Mauro Felippe","description":"Autor e Escritor","publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/maurofelippe.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb","name":"Mauro Felippe","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","width":164,"height":86,"caption":"Mauro Felippe"},"logo":{"@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png"},"sameAs":["http:\/\/www.maurofelippe.com"]}]}},"jetpack_shortlink":"https:\/\/wp.me\/PavqH1-w","jetpack-related-posts":[{"id":673,"url":"https:\/\/maurofelippe.com\/br\/artigos\/","url_meta":{"origin":32,"position":0},"title":"Artigos","author":"Mauro Felippe","date":"12\/12\/2018","format":false,"excerpt":"Leia artigos sobre o Mauro Felippe","rel":"","context":"Post similar","block_context":{"text":"Post similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":26,"url":"https:\/\/maurofelippe.com\/br\/reflexoes-e-cronicas\/","url_meta":{"origin":32,"position":1},"title":"Reflex\u00f5es e Cr\u00f4nicas","author":"Mauro Felippe","date":"24\/07\/2018","format":false,"excerpt":"Leia Reflex\u00f5es e Cr\u00f4nicas","rel":"","context":"Post similar","block_context":{"text":"Post similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":848,"url":"https:\/\/maurofelippe.com\/br\/materias-publicadas\/","url_meta":{"origin":32,"position":2},"title":"Mat\u00e9rias publicadas","author":"Mauro Felippe","date":"14\/12\/2018","format":false,"excerpt":"Leia mat\u00e9rias publicadas sobre o Mauro Felippe","rel":"","context":"Post similar","block_context":{"text":"Post similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":30,"url":"https:\/\/maurofelippe.com\/br\/fotos\/","url_meta":{"origin":32,"position":3},"title":"Fotos","author":"Mauro Felippe","date":"24\/07\/2018","format":false,"excerpt":"Fotos e Redes sociais Siga o Mauro Felippe nas redes sociais: Facebook Instagram Youtube","rel":"","context":"Post similar","block_context":{"text":"Post similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":125,"url":"https:\/\/maurofelippe.com\/br\/contato\/","url_meta":{"origin":32,"position":4},"title":"Contato","author":"Mauro Felippe","date":"30\/07\/2018","format":false,"excerpt":"ENTRE EM CONTATO COM O ESCRITOR MAURO FELIPPE Preencha o formul\u00e1rio a seguir para entrar em contato com o escritor Mauro Felippe.","rel":"","context":"Post similar","block_context":{"text":"Post similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2,"url":"https:\/\/maurofelippe.com\/br\/","url_meta":{"origin":32,"position":5},"title":"Home","author":"Mauro Felippe","date":"18\/07\/2018","format":false,"excerpt":"Anterior Pr\u00f3ximo https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/03\/Teaser-Catarse-fullHD-v3.mp4 Conhe\u00e7a minhas obras Cartase Lorem ipsum dolor sit amet, consectetur adipiscing elit. Proin ultricies sem lorem, non Adicione seu e-mail e receba novidades Artigos, eventos e imprensa","rel":"","context":"Post similar","block_context":{"text":"Post similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/04\/Catarse-Capa-menor-182x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/pages\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/comments?post=32"}],"version-history":[{"count":8,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/pages\/32\/revisions"}],"predecessor-version":[{"id":1886,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/pages\/32\/revisions\/1886"}],"wp:attachment":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/media?parent=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}