{"id":1100,"date":"2019-05-23T12:25:36","date_gmt":"2019-05-23T15:25:36","guid":{"rendered":"https:\/\/maurofelippe.com\/?p=1100"},"modified":"2019-05-23T12:25:36","modified_gmt":"2019-05-23T15:25:36","slug":"precisamos-proteger-nossas-criancas","status":"publish","type":"post","link":"https:\/\/maurofelippe.com\/br\/precisamos-proteger-nossas-criancas\/","title":{"rendered":"Precisamos proteger nossas crian\u00e7as"},"content":{"rendered":"<p>A viol\u00eancia contra a crian\u00e7a \u00e9 um assunto que desperta o interesse da sociedade que procura ajudar e solucionar essa problem\u00e1tica. Quando uma crian\u00e7a \u00e9 agredida as marcas n\u00e3o ficam apenas no corpo, mas tamb\u00e9m em sua mem\u00f3ria e no emocional. A agress\u00e3o sofrida atinge a infante no seu desenvolvimento e acaba interferindo na sua vis\u00e3o de mundo, afetando assim, diretamente, no indiv\u00edduo que se tornar\u00e1.<\/p>\n<p>Os n\u00fameros de den\u00fancias s\u00e3o alarmantes e os dados nem sempre s\u00e3o precisos, pois, nem todos os casos s\u00e3o relatados \u00e0s autoridades ou respons\u00e1veis. Todos os dias, no mundo inteiro, os pequeninos s\u00e3o v\u00edtimas de abusos, trabalho infantil, agress\u00f5es f\u00edsicas e psicol\u00f3gicas, dentre muitas outras formas de viol\u00eancia, incluindo a dom\u00e9stica o abuso sexual. Isso ocorre em todos os lugares, mas \u00e9 muito comum no \u00e2mbito familiar, como dito, justamente um lugar que eles deveriam se sentirem protegidos e seguros.<\/p>\n<p>Combater a agress\u00e3o infantil n\u00e3o \u00e9 nada f\u00e1cil, principalmente considerando que muitas vezes os menores n\u00e3o t\u00eam coragem de contar que est\u00e3o sendo v\u00edtima de maus tratos e viol\u00eancia, por raz\u00f5es associadas ao medo e, \u00e0s vezes, \u00e0 vergonha. Por isso, \u00e9 preciso que os adultos respons\u00e1veis estejam atentos a quaisquer sinais de mudan\u00e7as de comportamento, tristeza e introspec\u00e7\u00e3o.<\/p>\n<p>Com o intuito de protestar e colocar esse assunto em debate, anualmente, o dia 4 de Junho \u00e9 dedicado ao\u00a0<strong>Dia Mundial das Crian\u00e7as V\u00edtimas de Agress\u00e3o.<\/strong>\u00a0Essa data foi criada pela ONU, em 1982, n\u00e3o para ser comemorada mas, sim, para que todos reflitam e relembrem atentamente acerca da problem\u00e1tica.<\/p>\n<p>O dia relembra todas as v\u00edtimas infantis e, com isso, chama a aten\u00e7\u00e3o para a necessidade de proteger nossas crian\u00e7as que se encontram em um momento fr\u00e1gil, educa-las, ajuda-las na constru\u00e7\u00e3o da mentalidade, do car\u00e1ter e dos valores.<\/p>\n<p>Ent\u00e3o, para que os casos de agress\u00f5es parem \u00e9 preciso garantir um ambiente seguro e agrad\u00e1vel para o crescimento de meninos e meninas. Isso \u00e9 um dever dos respons\u00e1veis, fam\u00edlias, comunidades locais, governantes e da sociedade num todo. Nunca devemos esquecer dos direitos das crian\u00e7as e dos adolescentes, como est\u00e1 disposto na\u00a0<strong><em>Constitui\u00e7\u00e3o Brasileira<\/em><\/strong>, no Artigo 227, e no\u00a0<strong><em>Estatuto da Crian\u00e7a e do Adolescente<\/em><\/strong>\u00a0(ECA), que tamb\u00e9m assegura a prote\u00e7\u00e3o integral daqueles.<\/p>\n<p><em>&#8220;\u00c9 dever da fam\u00edlia, da sociedade e do Estado assegurar \u00e0 crian\u00e7a e ao adolescente, com absoluta prioridade, o direito \u00e0 vida, \u00e0 sa\u00fade, \u00e0 alimenta\u00e7\u00e3o, \u00e0 educa\u00e7\u00e3o, ao lazer, \u00e0 profissionaliza\u00e7\u00e3o, \u00e0 cultura, \u00e0 dignidade, ao respeito, \u00e0 liberdade e \u00e0 conviv\u00eancia familiar e comunit\u00e1ria, al\u00e9m de coloc\u00e1-los a salvo de toda forma de neglig\u00eancia, discrimina\u00e7\u00e3o, explora\u00e7\u00e3o, viol\u00eancia, crueldade e opress\u00e3o.&#8221; (CF 1988, Art. 227,<\/em>\u00a0<em>Cap\u00edtulo VII).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A viol\u00eancia contra a crian\u00e7a \u00e9 um assunto que desperta o interesse da sociedade que procura ajudar e solucionar essa problem\u00e1tica. Quando uma crian\u00e7a \u00e9 agredida as marcas n\u00e3o ficam apenas no corpo, mas tamb\u00e9m em sua mem\u00f3ria e no emocional. A agress\u00e3o sofrida atinge a infante no seu desenvolvimento e acaba interferindo na sua [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,31],"tags":[355,144,357,262,361,359,356,358,33,360],"class_list":["post-1100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-reflexao-e-cronicas","tag-advogado","tag-artigo","tag-artigo-227","tag-criancas","tag-cuidados","tag-dia-mundial-das-criancas-vitimas-de-agressao","tag-estatuto-da-crianca-e-do-adolescente","tag-familia","tag-mauro-felippe","tag-violencia"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Precisamos proteger nossas crian\u00e7as - Mauro Felippe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maurofelippe.com\/br\/precisamos-proteger-nossas-criancas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Precisamos proteger nossas crian\u00e7as - Mauro Felippe\" \/>\n<meta property=\"og:description\" content=\"A viol\u00eancia contra a crian\u00e7a \u00e9 um assunto que desperta o interesse da sociedade que procura ajudar e solucionar essa problem\u00e1tica. Quando uma crian\u00e7a \u00e9 agredida as marcas n\u00e3o ficam apenas no corpo, mas tamb\u00e9m em sua mem\u00f3ria e no emocional. A agress\u00e3o sofrida atinge a infante no seu desenvolvimento e acaba interferindo na sua [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maurofelippe.com\/br\/precisamos-proteger-nossas-criancas\/\" \/>\n<meta property=\"og:site_name\" content=\"Mauro Felippe\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-23T15:25:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/grupo-de-criancas-amigos-abracados-sentados-juntos_1150-3907.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"626\" \/>\n\t<meta property=\"og:image:height\" content=\"417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mauro Felippe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mauro Felippe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/precisamos-proteger-nossas-criancas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/precisamos-proteger-nossas-criancas\\\/\"},\"author\":{\"name\":\"Mauro Felippe\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"headline\":\"Precisamos proteger nossas crian\u00e7as\",\"datePublished\":\"2019-05-23T15:25:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/precisamos-proteger-nossas-criancas\\\/\"},\"wordCount\":487,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"image\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/precisamos-proteger-nossas-criancas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/grupo-de-criancas-amigos-abracados-sentados-juntos_1150-3907.jpg\",\"keywords\":[\"Advogado\",\"artigo\",\"Artigo 227\",\"crian\u00e7as\",\"Cuidados\",\"Dia Mundial das Crian\u00e7as V\u00edtimas de Agress\u00e3o\",\"Estatuto da Crian\u00e7a e do Adolescente\",\"Fam\u00edlia\",\"Mauro Felippe\",\"Viol\u00eancia\"],\"articleSection\":[\"Artigos\",\"Reflex\u00e3o e Cr\u00f4nicas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maurofelippe.com\\\/en\\\/precisamos-proteger-nossas-criancas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/precisamos-proteger-nossas-criancas\\\/\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/precisamos-proteger-nossas-criancas\\\/\",\"name\":\"Precisamos proteger nossas crian\u00e7as - Mauro Felippe\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/precisamos-proteger-nossas-criancas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/precisamos-proteger-nossas-criancas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/grupo-de-criancas-amigos-abracados-sentados-juntos_1150-3907.jpg\",\"datePublished\":\"2019-05-23T15:25:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/precisamos-proteger-nossas-criancas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maurofelippe.com\\\/en\\\/precisamos-proteger-nossas-criancas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/precisamos-proteger-nossas-criancas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/grupo-de-criancas-amigos-abracados-sentados-juntos_1150-3907.jpg\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/grupo-de-criancas-amigos-abracados-sentados-juntos_1150-3907.jpg\",\"width\":626,\"height\":417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/precisamos-proteger-nossas-criancas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maurofelippe.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Precisamos proteger nossas crian\u00e7as\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\",\"url\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/\",\"name\":\"Mauro Felippe\",\"description\":\"Autor e Escritor\",\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\",\"name\":\"Mauro Felippe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"width\":164,\"height\":86,\"caption\":\"Mauro Felippe\"},\"logo\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\"},\"sameAs\":[\"http:\\\/\\\/www.maurofelippe.com\"],\"url\":\"https:\\\/\\\/maurofelippe.com\\\/br\\\/author\\\/lc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Precisamos proteger nossas crian\u00e7as - Mauro Felippe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maurofelippe.com\/br\/precisamos-proteger-nossas-criancas\/","og_locale":"pt_BR","og_type":"article","og_title":"Precisamos proteger nossas crian\u00e7as - Mauro Felippe","og_description":"A viol\u00eancia contra a crian\u00e7a \u00e9 um assunto que desperta o interesse da sociedade que procura ajudar e solucionar essa problem\u00e1tica. Quando uma crian\u00e7a \u00e9 agredida as marcas n\u00e3o ficam apenas no corpo, mas tamb\u00e9m em sua mem\u00f3ria e no emocional. A agress\u00e3o sofrida atinge a infante no seu desenvolvimento e acaba interferindo na sua [&hellip;]","og_url":"https:\/\/maurofelippe.com\/br\/precisamos-proteger-nossas-criancas\/","og_site_name":"Mauro Felippe","article_published_time":"2019-05-23T15:25:36+00:00","og_image":[{"width":626,"height":417,"url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/grupo-de-criancas-amigos-abracados-sentados-juntos_1150-3907.jpg","type":"image\/jpeg"}],"author":"Mauro Felippe","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mauro Felippe","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maurofelippe.com\/en\/precisamos-proteger-nossas-criancas\/#article","isPartOf":{"@id":"https:\/\/maurofelippe.com\/en\/precisamos-proteger-nossas-criancas\/"},"author":{"name":"Mauro Felippe","@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"headline":"Precisamos proteger nossas crian\u00e7as","datePublished":"2019-05-23T15:25:36+00:00","mainEntityOfPage":{"@id":"https:\/\/maurofelippe.com\/en\/precisamos-proteger-nossas-criancas\/"},"wordCount":487,"commentCount":0,"publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"image":{"@id":"https:\/\/maurofelippe.com\/en\/precisamos-proteger-nossas-criancas\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/grupo-de-criancas-amigos-abracados-sentados-juntos_1150-3907.jpg","keywords":["Advogado","artigo","Artigo 227","crian\u00e7as","Cuidados","Dia Mundial das Crian\u00e7as V\u00edtimas de Agress\u00e3o","Estatuto da Crian\u00e7a e do Adolescente","Fam\u00edlia","Mauro Felippe","Viol\u00eancia"],"articleSection":["Artigos","Reflex\u00e3o e Cr\u00f4nicas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maurofelippe.com\/en\/precisamos-proteger-nossas-criancas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maurofelippe.com\/en\/precisamos-proteger-nossas-criancas\/","url":"https:\/\/maurofelippe.com\/en\/precisamos-proteger-nossas-criancas\/","name":"Precisamos proteger nossas crian\u00e7as - Mauro Felippe","isPartOf":{"@id":"http:\/\/maurofelippe.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maurofelippe.com\/en\/precisamos-proteger-nossas-criancas\/#primaryimage"},"image":{"@id":"https:\/\/maurofelippe.com\/en\/precisamos-proteger-nossas-criancas\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/grupo-de-criancas-amigos-abracados-sentados-juntos_1150-3907.jpg","datePublished":"2019-05-23T15:25:36+00:00","breadcrumb":{"@id":"https:\/\/maurofelippe.com\/en\/precisamos-proteger-nossas-criancas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maurofelippe.com\/en\/precisamos-proteger-nossas-criancas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maurofelippe.com\/en\/precisamos-proteger-nossas-criancas\/#primaryimage","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/grupo-de-criancas-amigos-abracados-sentados-juntos_1150-3907.jpg","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/grupo-de-criancas-amigos-abracados-sentados-juntos_1150-3907.jpg","width":626,"height":417},{"@type":"BreadcrumbList","@id":"https:\/\/maurofelippe.com\/en\/precisamos-proteger-nossas-criancas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maurofelippe.com\/"},{"@type":"ListItem","position":2,"name":"Precisamos proteger nossas crian\u00e7as"}]},{"@type":"WebSite","@id":"http:\/\/maurofelippe.com\/br\/#website","url":"http:\/\/maurofelippe.com\/br\/","name":"Mauro Felippe","description":"Autor e Escritor","publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/maurofelippe.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb","name":"Mauro Felippe","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","width":164,"height":86,"caption":"Mauro Felippe"},"logo":{"@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png"},"sameAs":["http:\/\/www.maurofelippe.com"],"url":"https:\/\/maurofelippe.com\/br\/author\/lc\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/grupo-de-criancas-amigos-abracados-sentados-juntos_1150-3907.jpg","jetpack_shortlink":"https:\/\/wp.me\/pavqH1-hK","jetpack-related-posts":[{"id":1110,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-jornal-impresso-folha-de-londrina\/","url_meta":{"origin":1100,"position":0},"title":"Mauro Felippe no jornal impresso Folha de Londrina","author":"Mauro Felippe","date":"30\/05\/2019","format":false,"excerpt":"O artigo completo \"Precisamos proteger nossas crian\u00e7as\" do autor, poeta e tamb\u00e9m advogado Mauro Felippe\u00a0 foi divulgado no jornal impresso Folha de Londrina - jornal do Paran\u00e1. Confira abaixo. \u00a0","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/files.pressmanager.net\/clientes\/64a8e8d576d3505a7823819ae1fa6eb7\/imagens\/2019\/05\/27\/755493b69d437b8bcb732ce5bcc512e2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/files.pressmanager.net\/clientes\/64a8e8d576d3505a7823819ae1fa6eb7\/imagens\/2019\/05\/27\/755493b69d437b8bcb732ce5bcc512e2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/files.pressmanager.net\/clientes\/64a8e8d576d3505a7823819ae1fa6eb7\/imagens\/2019\/05\/27\/755493b69d437b8bcb732ce5bcc512e2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/files.pressmanager.net\/clientes\/64a8e8d576d3505a7823819ae1fa6eb7\/imagens\/2019\/05\/27\/755493b69d437b8bcb732ce5bcc512e2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1175,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-jornal-folha-de-londrina\/","url_meta":{"origin":1100,"position":1},"title":"Mauro Felippe no jornal Folha de Londrina!","author":"Mauro Felippe","date":"17\/07\/2019","format":false,"excerpt":"O artigo \"Precisamos Proteger nossas Crian\u00e7as\", escrito pelo poeta e advogado Mauro Felippe foi replicado no jornal impresso Folha de Londrina! Confira:","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/files.pressmanager.net\/clientes\/64a8e8d576d3505a7823819ae1fa6eb7\/imagens\/2019\/05\/27\/755493b69d437b8bcb732ce5bcc512e2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/files.pressmanager.net\/clientes\/64a8e8d576d3505a7823819ae1fa6eb7\/imagens\/2019\/05\/27\/755493b69d437b8bcb732ce5bcc512e2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/files.pressmanager.net\/clientes\/64a8e8d576d3505a7823819ae1fa6eb7\/imagens\/2019\/05\/27\/755493b69d437b8bcb732ce5bcc512e2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":954,"url":"https:\/\/maurofelippe.com\/br\/dia-do-livro-didatico-a-importancia-da-educacao\/","url_meta":{"origin":1100,"position":2},"title":"Dia do livro did\u00e1tico: A import\u00e2ncia da educa\u00e7\u00e3o","author":"Mauro Felippe","date":"15\/02\/2019","format":false,"excerpt":"Nesse 27 de fevereiro comemora-se o Dia Nacional do Livro Did\u00e1tico, material essencial para que crian\u00e7as de todo o Brasil possam aprender e estender os seus conhecimentos \u201cPapai Rato rima com gato Avestruz rima com luz Filho rima com milho - E mam\u00e3e, rima com o que? Vejam meus filhos:\u2026","rel":"","context":"Em &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/br\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/02\/rptgtpxd-1396254731.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/02\/rptgtpxd-1396254731.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/02\/rptgtpxd-1396254731.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/02\/rptgtpxd-1396254731.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/02\/rptgtpxd-1396254731.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":820,"url":"https:\/\/maurofelippe.com\/br\/dia-das-criancas-a-saudosidade-da-infancia\/","url_meta":{"origin":1100,"position":3},"title":"Dia das crian\u00e7as: a saudosidade da inf\u00e2ncia","author":"Mauro Felippe","date":"13\/12\/2018","format":false,"excerpt":"Minha inf\u00e2ncia passou Quero v\u00ea-la voltar Mas... Como n\u00e3o mais conseguirei Reflito \u00e0s crian\u00e7as tudo que buscar O trecho acima \u00e9 do poema \u201cSaudades da inf\u00e2ncia\u201d, escrito pelo poeta Mauro Felippe, sobre as inoc\u00eancias presentes na juventude, sobre as energias e liberdades que as crian\u00e7as possuem. Muitas pessoas se veem\u2026","rel":"","context":"Em &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/br\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/crian%C3%A7a-brincando-de-amarelinha-Por-que-os-adultos-complicam-tanto-a-inf%C3%A2ncia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/crian%C3%A7a-brincando-de-amarelinha-Por-que-os-adultos-complicam-tanto-a-inf%C3%A2ncia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/crian%C3%A7a-brincando-de-amarelinha-Por-que-os-adultos-complicam-tanto-a-inf%C3%A2ncia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/crian%C3%A7a-brincando-de-amarelinha-Por-que-os-adultos-complicam-tanto-a-inf%C3%A2ncia.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/crian%C3%A7a-brincando-de-amarelinha-Por-que-os-adultos-complicam-tanto-a-inf%C3%A2ncia.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/crian%C3%A7a-brincando-de-amarelinha-Por-que-os-adultos-complicam-tanto-a-inf%C3%A2ncia.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":1002,"url":"https:\/\/maurofelippe.com\/br\/infancia-uma-das-fases-mais-importantes-da-vida\/","url_meta":{"origin":1100,"position":4},"title":"Inf\u00e2ncia: uma das fases mais importantes da vida","author":"Mauro Felippe","date":"20\/03\/2019","format":false,"excerpt":"Estabelecido pela UNICEF, o Dia Mundial da Inf\u00e2ncia \u00e9 comemorado em 21 de Mar\u00e7o, com o prop\u00f3sito de conscientizar a popula\u00e7\u00e3o sobre a import\u00e2ncia de uma boa forma\u00e7\u00e3o social infantil No dia 21 de Mar\u00e7o, comemora-se o Dia Mundial da Inf\u00e2ncia. A data, estabelecida pelo Fundo das Na\u00e7\u00f5es Unidas para\u2026","rel":"","context":"Em &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/br\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/criancas__2_.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/criancas__2_.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/criancas__2_.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/criancas__2_.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/criancas__2_.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/criancas__2_.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":990,"url":"https:\/\/maurofelippe.com\/br\/escola-lugar-de-maior-importancia-para-a-formacao-educacional-da-populacao\/","url_meta":{"origin":1100,"position":5},"title":"Escola: lugar de maior import\u00e2ncia para a forma\u00e7\u00e3o educacional da popula\u00e7\u00e3o","author":"Mauro Felippe","date":"11\/03\/2019","format":false,"excerpt":"Uma institui\u00e7\u00e3o que \u00e9 t\u00e3o importante para o mundo n\u00e3o poderia deixar de ser homenageada, no dia 15 de mar\u00e7o \u00e9 comemorado o Dia da Escola \u201cPapai Rato rima com gato Avestruz rima com luz Filho rima com milho - E mam\u00e3e, rima com o que? Vejam meus filhos: N\u00e3o\u2026","rel":"","context":"Em &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/br\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/formacao_qual-e-a-finalidade-de-inserir-a-ideologia-de-genero-nas-escolas-1600x1200.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/formacao_qual-e-a-finalidade-de-inserir-a-ideologia-de-genero-nas-escolas-1600x1200.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/formacao_qual-e-a-finalidade-de-inserir-a-ideologia-de-genero-nas-escolas-1600x1200.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/formacao_qual-e-a-finalidade-de-inserir-a-ideologia-de-genero-nas-escolas-1600x1200.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/formacao_qual-e-a-finalidade-de-inserir-a-ideologia-de-genero-nas-escolas-1600x1200.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/formacao_qual-e-a-finalidade-de-inserir-a-ideologia-de-genero-nas-escolas-1600x1200.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/1100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/comments?post=1100"}],"version-history":[{"count":1,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/1100\/revisions"}],"predecessor-version":[{"id":1102,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/1100\/revisions\/1102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/media\/1101"}],"wp:attachment":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/media?parent=1100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/categories?post=1100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/tags?post=1100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}