{"id":1132,"date":"2019-07-12T10:55:07","date_gmt":"2019-07-12T13:55:07","guid":{"rendered":"https:\/\/maurofelippe.com\/?p=1132"},"modified":"2019-07-12T12:59:58","modified_gmt":"2019-07-12T15:59:58","slug":"o-rock-que-influencia-a-vida","status":"publish","type":"post","link":"https:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/","title":{"rendered":"O Rock que influencia a vida"},"content":{"rendered":"<p>Anualmente, no dia 13 de julho comemora-se o\u00a0<strong>Dia Mundial do Rock<\/strong>. Esta data \u00e9 uma bela homenagem ao famoso estilo\u00a0<em>Rock in Roll<\/em>, que revolucionou a m\u00fasica e o comportamento social, al\u00e9m da cultural jovem na segunda metade do s\u00e9culo XX.<\/p>\n<p>Esse g\u00eanero musical, composto por indiv\u00edduos que s\u00e3o muitas vezes antag\u00f4nicos, continua com o mesmo prop\u00f3sito original: lutar pela liberdade de express\u00e3o usando suas letras t\u00e3o significantes e geniais. Esse ritmo influenciou, e influencia, diversas pessoas ao redor do mundo, e comigo n\u00e3o foi e n\u00e3o \u00e9 diferente&#8230;<\/p>\n<p><strong>A musicalidade no meu cotidiano<\/strong><\/p>\n<p>Devo admitir que o Rock sempre me fascinou, desde quando tive o primeiro contato com seus ritmos, o peso dos instrumentos, melodias e letras. A partir disso, as bandas e as m\u00fasicas viraram as minhas acompanhantes di\u00e1rias, enquanto descanso, escrevo, viajo e vivo, desde minha adolesc\u00eancia at\u00e9 hoje e assim sempre ser\u00e1! N\u00e3o \u00e9 por acaso que, quando escrevo ou descanso, estou com um dos meus aparelhos de som ligado, tocando as minhas bandas favoritas. Sem d\u00favidas elas se harmonizam com o processo criativo de cada poema e artigo produzido, sem contar com minha vida.<\/p>\n<p>Creio que a m\u00fasica e a criatividade sempre andam juntas. A m\u00fasica \u00e9 um dos alimentos da alma. J\u00e1 escrevera sobre este tema, em forma de aforismo, em um dos meus livros. \u00c9 uma perfeita sintonia daqueles dois elementos extremamente essenciais para a qualidade de um bom trabalho e de uma escrita din\u00e2mica e envolvente. N\u00e3o saberia viver os meus momentos de \u00f3cio criativo sem a m\u00fasica.<\/p>\n<p>O Rock, em sua ess\u00eancia mais pura, \u00e9 uma combina\u00e7\u00e3o harmoniosa de v\u00e1rios elementos, tais como: notas, tons, arranjo, for\u00e7a, sentimento, t\u00e9cnica, entre in\u00fameros outros. Assim \u00e9 na poesia tamb\u00e9m! Sempre devemos procurar inspira\u00e7\u00e3o, deixar o sentimento solto, ter melodia e musicalidade em cada verso e estrofe. Desta forma, toca o leitor assim como a m\u00fasica toca a alma de seus ouvintes, profundamente.<\/p>\n<p><strong>O Rock e a Escrita<\/strong><\/p>\n<p>A imagina\u00e7\u00e3o, as palavras de um poema e o som do rock n\u00e3o s\u00e3o uma t\u00e9cnica em si. N\u00e3o s\u00e3o palp\u00e1veis, s\u00e3o ess\u00eancias. O ritmo musical \u00ad\u2013 assim como os de um poema, acredito eu \u2013 toca o cora\u00e7\u00e3o, n\u00e3o s\u00f3 de quem canta ou escreve, mas de quem recebe o conte\u00fado. Tocam todos os nossos sentidos de uma forma m\u00e1gica e \u00fanica. Indescrit\u00edvel!<\/p>\n<p>Diante disso, afirmo: as can\u00e7\u00f5es est\u00e3o ligadas \u00e0s mem\u00f3rias afetivas, por isso, influenciam diretamente no nosso estado de esp\u00edrito e ativa fun\u00e7\u00f5es cerebrais que nos remetem tantos tempos j\u00e1 vividos, tantas lembran\u00e7as preciosas. A cada som, lembro-me da inf\u00e2ncia, da juventude, no local exato onde me encontrava &#8230; e minha m\u00e3o desliza pelo papel, prontamente. A maioria dos meus textos ou ideias nasceu ouvindo m\u00fasicas que me tocaram, no momento, no fundo da alma e do cora\u00e7\u00e3o.<\/p>\n<p>Por fim, agrade\u00e7o grandemente os sentidos que me agu\u00e7aram e continuam vibrantes. Eu, falar de m\u00fasica neste pequeno espa\u00e7o seria injusto comigo mesmo. N\u00e3o h\u00e1 espa\u00e7o suficiente para descrever a minha liga\u00e7\u00e3o principalmente com o Rock de boa qualidade (o Hard Rock, o Progressivo, o Heavy Metal, o Jazz Fusion, etc), sem descartar a MPB cl\u00e1ssica, obviamente. Agrade\u00e7o as bandas de rock que sempre ouvi e que me ajudam \u2013 me incentivam a continuar \u2013 a escrever, a criar tantos poemas. Ent\u00e3o, para finalizar, indico aqui algumas bandas essenciais que s\u00e3o fontes das minhas inspira\u00e7\u00f5es mais profundas e dos meus versos mais belos. N\u00e3o est\u00e3o na ordem de prefer\u00eancia. LONGA VIDA AO ROCK N\u2019 ROLL!<\/p>\n<ul>\n<li>Black Sabbath;<\/li>\n<li>Rush;<\/li>\n<li>Yes;<\/li>\n<li>Genesis;<\/li>\n<li>Iron Maiden;<\/li>\n<li>14 Bis (nacional);<\/li>\n<li>Casa das M\u00e1quinas (nacional);<\/li>\n<li>O Ter\u00e7o (nacional);<\/li>\n<li>Ira! (nacional);<\/li>\n<li>Rainbow;<\/li>\n<li>Ufo;<\/li>\n<li>Deep Purple;<\/li>\n<li>Marillion;<\/li>\n<li>Pink Floyd;<\/li>\n<li>Led Zeppelin;<\/li>\n<li>Queen;<\/li>\n<li>Uriah Heep;<\/li>\n<li>Nazareth; dentre muitas outras que as considero cl\u00e1ssicas, atemporais.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Anualmente, no dia 13 de julho comemora-se o\u00a0Dia Mundial do Rock. Esta data \u00e9 uma bela homenagem ao famoso estilo\u00a0Rock in Roll, que revolucionou a m\u00fasica e o comportamento social, al\u00e9m da cultural jovem na segunda metade do s\u00e9culo XX. Esse g\u00eanero musical, composto por indiv\u00edduos que s\u00e3o muitas vezes antag\u00f4nicos, continua com o mesmo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1135,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[31,1],"tags":[397,395,400,399,38,43,33,188,352,398,396,401],"class_list":["post-1132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reflexao-e-cronicas","category-sem-categoria","tag-artigo-de-opiniao","tag-dia-do-rock","tag-hard-rock","tag-heavy-metal","tag-literatura","tag-livros","tag-mauro-felippe","tag-musica","tag-poesias","tag-rock","tag-rock-n-roll","tag-variedades"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O Rock que influencia a vida - Mauro Felippe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O Rock que influencia a vida - Mauro Felippe\" \/>\n<meta property=\"og:description\" content=\"Anualmente, no dia 13 de julho comemora-se o\u00a0Dia Mundial do Rock. Esta data \u00e9 uma bela homenagem ao famoso estilo\u00a0Rock in Roll, que revolucionou a m\u00fasica e o comportamento social, al\u00e9m da cultural jovem na segunda metade do s\u00e9culo XX. Esse g\u00eanero musical, composto por indiv\u00edduos que s\u00e3o muitas vezes antag\u00f4nicos, continua com o mesmo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Mauro Felippe\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-12T13:55:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-12T15:59:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/07\/maxresdefault.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mauro Felippe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mauro Felippe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/o-rock-que-influencia-a-vida\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/o-rock-que-influencia-a-vida\\\/\"},\"author\":{\"name\":\"Mauro Felippe\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"headline\":\"O Rock que influencia a vida\",\"datePublished\":\"2019-07-12T13:55:07+00:00\",\"dateModified\":\"2019-07-12T15:59:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/o-rock-que-influencia-a-vida\\\/\"},\"wordCount\":686,\"commentCount\":2,\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"image\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/o-rock-que-influencia-a-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/maxresdefault.jpg\",\"keywords\":[\"Artigo de opini\u00e3o\",\"Dia do Rock\",\"Hard Rock\",\"Heavy Metal\",\"literatura\",\"livros\",\"Mauro Felippe\",\"musica\",\"Poesias\",\"Rock\",\"Rock n' roll\",\"variedades\"],\"articleSection\":[\"Reflex\u00e3o e Cr\u00f4nicas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/maurofelippe.com\\\/br\\\/o-rock-que-influencia-a-vida\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/o-rock-que-influencia-a-vida\\\/\",\"url\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/o-rock-que-influencia-a-vida\\\/\",\"name\":\"O Rock que influencia a vida - Mauro Felippe\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/o-rock-que-influencia-a-vida\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/o-rock-que-influencia-a-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/maxresdefault.jpg\",\"datePublished\":\"2019-07-12T13:55:07+00:00\",\"dateModified\":\"2019-07-12T15:59:58+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/o-rock-que-influencia-a-vida\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/maurofelippe.com\\\/br\\\/o-rock-que-influencia-a-vida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/o-rock-que-influencia-a-vida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/maxresdefault.jpg\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/maxresdefault.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/o-rock-que-influencia-a-vida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maurofelippe.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O Rock que influencia a vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\",\"url\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/\",\"name\":\"Mauro Felippe\",\"description\":\"Autor e Escritor\",\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\",\"name\":\"Mauro Felippe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"width\":164,\"height\":86,\"caption\":\"Mauro Felippe\"},\"logo\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\"},\"sameAs\":[\"http:\\\/\\\/www.maurofelippe.com\"],\"url\":\"https:\\\/\\\/maurofelippe.com\\\/br\\\/author\\\/lc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Rock que influencia a vida - Mauro Felippe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/","og_locale":"pt_BR","og_type":"article","og_title":"O Rock que influencia a vida - Mauro Felippe","og_description":"Anualmente, no dia 13 de julho comemora-se o\u00a0Dia Mundial do Rock. Esta data \u00e9 uma bela homenagem ao famoso estilo\u00a0Rock in Roll, que revolucionou a m\u00fasica e o comportamento social, al\u00e9m da cultural jovem na segunda metade do s\u00e9culo XX. Esse g\u00eanero musical, composto por indiv\u00edduos que s\u00e3o muitas vezes antag\u00f4nicos, continua com o mesmo [&hellip;]","og_url":"http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/","og_site_name":"Mauro Felippe","article_published_time":"2019-07-12T13:55:07+00:00","article_modified_time":"2019-07-12T15:59:58+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/07\/maxresdefault.jpg","type":"image\/jpeg"}],"author":"Mauro Felippe","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mauro Felippe","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/#article","isPartOf":{"@id":"http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/"},"author":{"name":"Mauro Felippe","@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"headline":"O Rock que influencia a vida","datePublished":"2019-07-12T13:55:07+00:00","dateModified":"2019-07-12T15:59:58+00:00","mainEntityOfPage":{"@id":"http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/"},"wordCount":686,"commentCount":2,"publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"image":{"@id":"http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/07\/maxresdefault.jpg","keywords":["Artigo de opini\u00e3o","Dia do Rock","Hard Rock","Heavy Metal","literatura","livros","Mauro Felippe","musica","Poesias","Rock","Rock n' roll","variedades"],"articleSection":["Reflex\u00e3o e Cr\u00f4nicas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/","url":"http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/","name":"O Rock que influencia a vida - Mauro Felippe","isPartOf":{"@id":"http:\/\/maurofelippe.com\/br\/#website"},"primaryImageOfPage":{"@id":"http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/#primaryimage"},"image":{"@id":"http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/07\/maxresdefault.jpg","datePublished":"2019-07-12T13:55:07+00:00","dateModified":"2019-07-12T15:59:58+00:00","breadcrumb":{"@id":"http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/#primaryimage","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/07\/maxresdefault.jpg","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/07\/maxresdefault.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"http:\/\/maurofelippe.com\/br\/o-rock-que-influencia-a-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maurofelippe.com\/"},{"@type":"ListItem","position":2,"name":"O Rock que influencia a vida"}]},{"@type":"WebSite","@id":"http:\/\/maurofelippe.com\/br\/#website","url":"http:\/\/maurofelippe.com\/br\/","name":"Mauro Felippe","description":"Autor e Escritor","publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/maurofelippe.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb","name":"Mauro Felippe","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","width":164,"height":86,"caption":"Mauro Felippe"},"logo":{"@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png"},"sameAs":["http:\/\/www.maurofelippe.com"],"url":"https:\/\/maurofelippe.com\/br\/author\/lc\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/07\/maxresdefault.jpg","jetpack_shortlink":"https:\/\/wp.me\/pavqH1-ig","jetpack-related-posts":[{"id":1138,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-jornal-impresso-a-uniao\/","url_meta":{"origin":1132,"position":0},"title":"Mauro Felippe no jornal impresso A Uni\u00e3o","author":"Mauro Felippe","date":"17\/07\/2019","format":false,"excerpt":"O artigo completo sobre o \"Dia do Rock\" (13 de julho) do autor, poeta e tamb\u00e9m advogado Mauro Felippe\u00a0 foi divulgado no jornal impresso A Uni\u00e3o. Confira abaixo o texto completo.","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/07\/A-uni%C3%A3o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/07\/A-uni%C3%A3o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/07\/A-uni%C3%A3o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/07\/A-uni%C3%A3o.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1037,"url":"https:\/\/maurofelippe.com\/br\/dia-do-indio-uma-heranca-cultural-e-etnica\/","url_meta":{"origin":1132,"position":1},"title":"Dia do \u00edndio: Uma heran\u00e7a cultural e \u00e9tnica","author":"Mauro Felippe","date":"11\/04\/2019","format":false,"excerpt":"Uma data especial para relembrar a import\u00e2ncia cultural e hist\u00f3rica dos \u00edndios, o dia 19 de Abril foi escolhido gra\u00e7as ao 1\u00b0 Congresso Indigenista Interamericano, que ocorreu em 1940 \u201cOs por eles chamados Amer\u00edndios daqui Falavam como \u00edndios Depois como os portugueses Americanos, ingleses Os Amer\u00edndios... [...] Tantas l\u00ednguas goela\u2026","rel":"","context":"Em &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/br\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_do_I%CC%81ndio.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_do_I%CC%81ndio.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_do_I%CC%81ndio.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_do_I%CC%81ndio.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_do_I%CC%81ndio.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_do_I%CC%81ndio.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":920,"url":"https:\/\/maurofelippe.com\/br\/dia-mundial-do-compositor-o-talento-para-criar-belas-melodias\/","url_meta":{"origin":1132,"position":2},"title":"Dia Mundial do Compositor: o talento para criar belas melodias","author":"Mauro Felippe","date":"15\/01\/2019","format":false,"excerpt":"A data do dia 15 de Janeiro, tem um significado especial para os amantes da m\u00fasica. Ela homenageia os compositores de todo mundo, talentosos artistas que criam novas, interessantes e sens\u00edveis melodias para as m\u00fasicas que tanto amamos. A origem do dia se deve a uma comemora\u00e7\u00e3o \u00e0 funda\u00e7\u00e3o da\u2026","rel":"","context":"Em &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/br\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/Dia-do-Compositor.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/Dia-do-Compositor.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/Dia-do-Compositor.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/Dia-do-Compositor.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/Dia-do-Compositor.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/Dia-do-Compositor.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":954,"url":"https:\/\/maurofelippe.com\/br\/dia-do-livro-didatico-a-importancia-da-educacao\/","url_meta":{"origin":1132,"position":3},"title":"Dia do livro did\u00e1tico: A import\u00e2ncia da educa\u00e7\u00e3o","author":"Mauro Felippe","date":"15\/02\/2019","format":false,"excerpt":"Nesse 27 de fevereiro comemora-se o Dia Nacional do Livro Did\u00e1tico, material essencial para que crian\u00e7as de todo o Brasil possam aprender e estender os seus conhecimentos \u201cPapai Rato rima com gato Avestruz rima com luz Filho rima com milho - E mam\u00e3e, rima com o que? Vejam meus filhos:\u2026","rel":"","context":"Em &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/br\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/02\/rptgtpxd-1396254731.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/02\/rptgtpxd-1396254731.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/02\/rptgtpxd-1396254731.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/02\/rptgtpxd-1396254731.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/02\/rptgtpxd-1396254731.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":1182,"url":"https:\/\/maurofelippe.com\/br\/dia-do-poeta-de-cordel-canto-ao-nordeste\/","url_meta":{"origin":1132,"position":4},"title":"Dia do Poeta de Cordel","author":"Mauro Felippe","date":"01\/08\/2019","format":false,"excerpt":"Canto ao Nordeste Manda buscar outro mangue Cheio de vida Em outubro, estarei aportando no Nordeste Onde o \u00e1rido vira poesia E, o sofrimento, cantoria no Agreste. \u00a0 Tenho medo de quando eu l\u00e1 chegar... Cheio de vida Ver tal sofrimento no luar do Sert\u00e3o Onde a noite seca tamb\u00e9m\u2026","rel":"","context":"Em &quot;Reflex\u00e3o e Cr\u00f4nicas&quot;","block_context":{"text":"Reflex\u00e3o e Cr\u00f4nicas","link":"https:\/\/maurofelippe.com\/br\/category\/reflexao-e-cronicas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/08\/cordeu.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1017,"url":"https:\/\/maurofelippe.com\/br\/a-mentira-e-suas-consequencias\/","url_meta":{"origin":1132,"position":5},"title":"A Mentira e suas consequ\u00eancias","author":"Mauro Felippe","date":"01\/04\/2019","format":false,"excerpt":"No Dia 1\u00b0 de Abril, comemora-se o Dia da Mentira, mas poucos conhecessem a origem mais popular desta data. A vers\u00e3o mais conhecida remete ao S\u00e9culo XVI na Fran\u00e7a. L\u00e1, a chegada do Ano Novo era comemorada durante uma semana, iniciando dia 25 de Mar\u00e7o \u00e0 1\u00b0 de Abril. Em\u2026","rel":"","context":"Em &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/br\/category\/artigos\/"},"img":{"alt_text":"A Mentira e suas consequ\u00eancias","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_da_Mentira.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_da_Mentira.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_da_Mentira.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_da_Mentira.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_da_Mentira.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_da_Mentira.png?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/1132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/comments?post=1132"}],"version-history":[{"count":2,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/1132\/revisions"}],"predecessor-version":[{"id":1137,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/1132\/revisions\/1137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/media\/1135"}],"wp:attachment":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/media?parent=1132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/categories?post=1132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/tags?post=1132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}