{"id":1343,"date":"2019-10-09T14:11:20","date_gmt":"2019-10-09T17:11:20","guid":{"rendered":"https:\/\/maurofelippe.com\/?p=1343"},"modified":"2019-10-09T14:11:20","modified_gmt":"2019-10-09T17:11:20","slug":"mauro-felippe-na-radio-ebc-fm","status":"publish","type":"post","link":"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-radio-ebc-fm\/","title":{"rendered":"Mauro Felippe na R\u00e1dio EBC FM"},"content":{"rendered":"<p>A R\u00e1dio EBC FM divulgou o livro &#8220;Palavras T\u00eam Vidas&#8221; do autor Mauro Felippe.<\/p>\n<p>Para ouvir a entrevista <a href=\"https:\/\/liliancomunica.com.br\/site\/entrevista-mauro-felippe-para-a-radio-mec-31-08-2019\" target=\"_blank\" rel=\"noopener noreferrer\">clique aqui<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A R\u00e1dio EBC FM divulgou o livro &#8220;Palavras T\u00eam Vidas&#8221; do autor Mauro Felippe. Para ouvir a entrevista clique aqui.<\/p>\n","protected":false},"author":2,"featured_media":1344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,176],"tags":[33,436,451],"class_list":["post-1343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-imprensa","category-materias-publicadas","tag-mauro-felippe","tag-palavras-tem-vidas","tag-radio-ebc-fm"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mauro Felippe na R\u00e1dio EBC FM - Mauro Felippe<\/title>\n<meta name=\"description\" content=\"A R\u00e1dio EBC FM divulgou o livro &quot;Palavras T\u00eam Vidas&quot; do autor Mauro Felippe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-radio-ebc-fm\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mauro Felippe na R\u00e1dio EBC FM - Mauro Felippe\" \/>\n<meta property=\"og:description\" content=\"A R\u00e1dio EBC FM divulgou o livro &quot;Palavras T\u00eam Vidas&quot; do autor Mauro Felippe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-radio-ebc-fm\/\" \/>\n<meta property=\"og:site_name\" content=\"Mauro Felippe\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-09T17:11:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/10\/ebc_radios.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mauro Felippe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mauro Felippe\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/mauro-felippe-na-radio-ebc-fm\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/mauro-felippe-na-radio-ebc-fm\\\/\"},\"author\":{\"name\":\"Mauro Felippe\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"headline\":\"Mauro Felippe na R\u00e1dio EBC FM\",\"datePublished\":\"2019-10-09T17:11:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/mauro-felippe-na-radio-ebc-fm\\\/\"},\"wordCount\":29,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"image\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/mauro-felippe-na-radio-ebc-fm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/ebc_radios.png\",\"keywords\":[\"Mauro Felippe\",\"palavras t\u00eam vidas\",\"R\u00e1dio EBC FM\"],\"articleSection\":[\"Imprensa\",\"Mat\u00e9rias publicadas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maurofelippe.com\\\/en\\\/mauro-felippe-na-radio-ebc-fm\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/mauro-felippe-na-radio-ebc-fm\\\/\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/mauro-felippe-na-radio-ebc-fm\\\/\",\"name\":\"Mauro Felippe na R\u00e1dio EBC FM - Mauro Felippe\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/mauro-felippe-na-radio-ebc-fm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/mauro-felippe-na-radio-ebc-fm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/ebc_radios.png\",\"datePublished\":\"2019-10-09T17:11:20+00:00\",\"description\":\"A R\u00e1dio EBC FM divulgou o livro \\\"Palavras T\u00eam Vidas\\\" do autor Mauro Felippe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/mauro-felippe-na-radio-ebc-fm\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maurofelippe.com\\\/en\\\/mauro-felippe-na-radio-ebc-fm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/mauro-felippe-na-radio-ebc-fm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/ebc_radios.png\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/ebc_radios.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/mauro-felippe-na-radio-ebc-fm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maurofelippe.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mauro Felippe na R\u00e1dio EBC FM\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\",\"url\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/\",\"name\":\"Mauro Felippe\",\"description\":\"Autor e Escritor\",\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\",\"name\":\"Mauro Felippe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"width\":164,\"height\":86,\"caption\":\"Mauro Felippe\"},\"logo\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\"},\"sameAs\":[\"http:\\\/\\\/www.maurofelippe.com\"],\"url\":\"https:\\\/\\\/maurofelippe.com\\\/br\\\/author\\\/lc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mauro Felippe na R\u00e1dio EBC FM - Mauro Felippe","description":"A R\u00e1dio EBC FM divulgou o livro \"Palavras T\u00eam Vidas\" do autor Mauro Felippe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-radio-ebc-fm\/","og_locale":"pt_BR","og_type":"article","og_title":"Mauro Felippe na R\u00e1dio EBC FM - Mauro Felippe","og_description":"A R\u00e1dio EBC FM divulgou o livro \"Palavras T\u00eam Vidas\" do autor Mauro Felippe.","og_url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-radio-ebc-fm\/","og_site_name":"Mauro Felippe","article_published_time":"2019-10-09T17:11:20+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/10\/ebc_radios.png","type":"image\/png"}],"author":"Mauro Felippe","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mauro Felippe"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maurofelippe.com\/en\/mauro-felippe-na-radio-ebc-fm\/#article","isPartOf":{"@id":"https:\/\/maurofelippe.com\/en\/mauro-felippe-na-radio-ebc-fm\/"},"author":{"name":"Mauro Felippe","@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"headline":"Mauro Felippe na R\u00e1dio EBC FM","datePublished":"2019-10-09T17:11:20+00:00","mainEntityOfPage":{"@id":"https:\/\/maurofelippe.com\/en\/mauro-felippe-na-radio-ebc-fm\/"},"wordCount":29,"commentCount":0,"publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"image":{"@id":"https:\/\/maurofelippe.com\/en\/mauro-felippe-na-radio-ebc-fm\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/10\/ebc_radios.png","keywords":["Mauro Felippe","palavras t\u00eam vidas","R\u00e1dio EBC FM"],"articleSection":["Imprensa","Mat\u00e9rias publicadas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maurofelippe.com\/en\/mauro-felippe-na-radio-ebc-fm\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maurofelippe.com\/en\/mauro-felippe-na-radio-ebc-fm\/","url":"https:\/\/maurofelippe.com\/en\/mauro-felippe-na-radio-ebc-fm\/","name":"Mauro Felippe na R\u00e1dio EBC FM - Mauro Felippe","isPartOf":{"@id":"http:\/\/maurofelippe.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maurofelippe.com\/en\/mauro-felippe-na-radio-ebc-fm\/#primaryimage"},"image":{"@id":"https:\/\/maurofelippe.com\/en\/mauro-felippe-na-radio-ebc-fm\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/10\/ebc_radios.png","datePublished":"2019-10-09T17:11:20+00:00","description":"A R\u00e1dio EBC FM divulgou o livro \"Palavras T\u00eam Vidas\" do autor Mauro Felippe.","breadcrumb":{"@id":"https:\/\/maurofelippe.com\/en\/mauro-felippe-na-radio-ebc-fm\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maurofelippe.com\/en\/mauro-felippe-na-radio-ebc-fm\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maurofelippe.com\/en\/mauro-felippe-na-radio-ebc-fm\/#primaryimage","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/10\/ebc_radios.png","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/10\/ebc_radios.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/maurofelippe.com\/en\/mauro-felippe-na-radio-ebc-fm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maurofelippe.com\/"},{"@type":"ListItem","position":2,"name":"Mauro Felippe na R\u00e1dio EBC FM"}]},{"@type":"WebSite","@id":"http:\/\/maurofelippe.com\/br\/#website","url":"http:\/\/maurofelippe.com\/br\/","name":"Mauro Felippe","description":"Autor e Escritor","publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/maurofelippe.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb","name":"Mauro Felippe","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","width":164,"height":86,"caption":"Mauro Felippe"},"logo":{"@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png"},"sameAs":["http:\/\/www.maurofelippe.com"],"url":"https:\/\/maurofelippe.com\/br\/author\/lc\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/10\/ebc_radios.png","jetpack_shortlink":"https:\/\/wp.me\/pavqH1-lF","jetpack-related-posts":[{"id":1340,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-radio-catedral-fm\/","url_meta":{"origin":1343,"position":0},"title":"Mauro Felippe na R\u00e1dio Catedral FM","author":"Mauro Felippe","date":"09\/10\/2019","format":false,"excerpt":"A R\u00e1dio Catedral FM divulgou o livro \"Palavras T\u00eam Vidas\" do autor Mauro Felippe. Para ouvir a entrevista clique aqui. \u00a0","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/10\/R%C3%A1dio-Catedral-FM.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1357,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-radio-ebc-fm-2\/","url_meta":{"origin":1343,"position":1},"title":"Mauro Felippe na R\u00e1dio EBC FM","author":"Mauro Felippe","date":"08\/11\/2019","format":false,"excerpt":"A R\u00e1dio EBC FM divulgou o livro \"Palavras T\u00eam Vidas\" do autor Mauro Felippe. Para ouvir a entrevista clique aqui.","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/10\/ebc_radios.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1335,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-radio-monte-carlo-fm\/","url_meta":{"origin":1343,"position":2},"title":"Mauro Felippe na R\u00e1dio Monte Carlo FM","author":"Mauro Felippe","date":"09\/10\/2019","format":false,"excerpt":"A R\u00e1dio Monte Carlo FM divulgou o livro \"Palavras T\u00eam Vidas\" do autor Mauro Felippe. Para ouvir a entrevista clique aqui.","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/10\/R%C3%A1dio-Monte-Carlo-FM.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":321,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-radio-justica\/","url_meta":{"origin":1343,"position":3},"title":"Mauro Felippe na R\u00e1dio Justi\u00e7a","author":"Mauro Felippe","date":"13\/11\/2018","format":false,"excerpt":"Confira a entrevista de Mauro Felippe na R\u00e1dio Justi\u00e7a O autor e advogado Mauro Felippe concedeu uma entrevista para a R\u00e1dio Justi\u00e7a no dia 29\/10","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/R%C3%A1dio-Justi%C3%A7a.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/R%C3%A1dio-Justi%C3%A7a.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/R%C3%A1dio-Justi%C3%A7a.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":576,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-radio-justica-2\/","url_meta":{"origin":1343,"position":4},"title":"Mauro Felippe na R\u00e1dio Justi\u00e7a","author":"Mauro Felippe","date":"07\/12\/2018","format":false,"excerpt":"Confira a entrevista na R\u00e1dio Justi\u00e7a sobre as obras do autor Mauro Felippe. O autor e advogado Mauro Felippe concedeu uma entrevista para a R\u00e1dio Justi\u00e7a no dia 29\/10.","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/R%C3%A1dio-Justi%C3%A7a.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/R%C3%A1dio-Justi%C3%A7a.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/R%C3%A1dio-Justi%C3%A7a.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":622,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-radio-senado-2\/","url_meta":{"origin":1343,"position":5},"title":"Mauro Felippe na R\u00e1dio Senado","author":"Mauro Felippe","date":"07\/12\/2018","format":false,"excerpt":"Confira a entrevista na R\u00e1dio Senado sobre as obras do autor Mauro Felippe. O poeta e advogado Mauro Felippe foi entrevistado na R\u00e1dio Senado para falar de seus livros, poesias e carreira.","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/R%C3%A1dio-SEnado.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/R%C3%A1dio-SEnado.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/R%C3%A1dio-SEnado.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/1343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/comments?post=1343"}],"version-history":[{"count":2,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/1343\/revisions"}],"predecessor-version":[{"id":1358,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/1343\/revisions\/1358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/media\/1344"}],"wp:attachment":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/media?parent=1343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/categories?post=1343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/tags?post=1343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}