{"id":1433,"date":"2020-03-02T10:14:01","date_gmt":"2020-03-02T13:14:01","guid":{"rendered":"https:\/\/maurofelippe.com\/?p=1433"},"modified":"2020-03-02T10:14:38","modified_gmt":"2020-03-02T13:14:38","slug":"mauro-felippe-na-revista-ana-maria","status":"publish","type":"post","link":"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/","title":{"rendered":"MAURO FELIPPE NA REVISTA ANA MARIA"},"content":{"rendered":"<p>A Revista Ana Maria divulgou o livro \u201cPalavras T\u00eam Vidas\u201d, do autor Mauro Felippe.<img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-1435\" src=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/2020-revista-ana-maria-2222.jpg\" alt=\"\" width=\"964\" height=\"964\" srcset=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/2020-revista-ana-maria-2222.jpg 964w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/2020-revista-ana-maria-2222-150x150.jpg 150w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/2020-revista-ana-maria-2222-300x300.jpg 300w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/2020-revista-ana-maria-2222-768x768.jpg 768w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/2020-revista-ana-maria-2222-256x256.jpg 256w\" sizes=\"(max-width: 964px) 100vw, 964px\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-1436\" src=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/capa_13844607.jpg\" alt=\"\" width=\"500\" height=\"658\" srcset=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/capa_13844607.jpg 500w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/capa_13844607-228x300.jpg 228w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><img decoding=\"async\" class=\"aligncenter size-full wp-image-1437\" src=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/revista-na-midia.jpg\" alt=\"\" width=\"480\" height=\"649\" srcset=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/revista-na-midia.jpg 480w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/revista-na-midia-222x300.jpg 222w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Revista Ana Maria divulgou o livro \u201cPalavras T\u00eam Vidas\u201d, do autor Mauro Felippe.<\/p>\n","protected":false},"author":2,"featured_media":1434,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[176],"tags":[33,328,436,461],"class_list":["post-1433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materias-publicadas","tag-mauro-felippe","tag-na-midia","tag-palavras-tem-vidas","tag-revista-ana-maria"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MAURO FELIPPE NA REVISTA ANA MARIA - Mauro Felippe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MAURO FELIPPE NA REVISTA ANA MARIA - Mauro Felippe\" \/>\n<meta property=\"og:description\" content=\"A Revista Ana Maria divulgou o livro \u201cPalavras T\u00eam Vidas\u201d, do autor Mauro Felippe.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/\" \/>\n<meta property=\"og:site_name\" content=\"Mauro Felippe\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-02T13:14:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-02T13:14:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/B0g4KELu_400x400.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mauro Felippe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mauro Felippe\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-na-revista-ana-maria\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-na-revista-ana-maria\\\/\"},\"author\":{\"name\":\"Mauro Felippe\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"headline\":\"MAURO FELIPPE NA REVISTA ANA MARIA\",\"datePublished\":\"2020-03-02T13:14:01+00:00\",\"dateModified\":\"2020-03-02T13:14:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-na-revista-ana-maria\\\/\"},\"wordCount\":21,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"image\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-na-revista-ana-maria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/B0g4KELu_400x400.jpg\",\"keywords\":[\"Mauro Felippe\",\"Na M\u00eddia\",\"palavras t\u00eam vidas\",\"Revista Ana Maria\"],\"articleSection\":[\"Mat\u00e9rias publicadas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-na-revista-ana-maria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-na-revista-ana-maria\\\/\",\"url\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-na-revista-ana-maria\\\/\",\"name\":\"MAURO FELIPPE NA REVISTA ANA MARIA - Mauro Felippe\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-na-revista-ana-maria\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-na-revista-ana-maria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/B0g4KELu_400x400.jpg\",\"datePublished\":\"2020-03-02T13:14:01+00:00\",\"dateModified\":\"2020-03-02T13:14:38+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-na-revista-ana-maria\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-na-revista-ana-maria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-na-revista-ana-maria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/B0g4KELu_400x400.jpg\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/B0g4KELu_400x400.jpg\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-na-revista-ana-maria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maurofelippe.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MAURO FELIPPE NA REVISTA ANA MARIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\",\"url\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/\",\"name\":\"Mauro Felippe\",\"description\":\"Autor e Escritor\",\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\",\"name\":\"Mauro Felippe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"width\":164,\"height\":86,\"caption\":\"Mauro Felippe\"},\"logo\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\"},\"sameAs\":[\"http:\\\/\\\/www.maurofelippe.com\"],\"url\":\"https:\\\/\\\/maurofelippe.com\\\/br\\\/author\\\/lc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MAURO FELIPPE NA REVISTA ANA MARIA - Mauro Felippe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/","og_locale":"pt_BR","og_type":"article","og_title":"MAURO FELIPPE NA REVISTA ANA MARIA - Mauro Felippe","og_description":"A Revista Ana Maria divulgou o livro \u201cPalavras T\u00eam Vidas\u201d, do autor Mauro Felippe.","og_url":"http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/","og_site_name":"Mauro Felippe","article_published_time":"2020-03-02T13:14:01+00:00","article_modified_time":"2020-03-02T13:14:38+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/B0g4KELu_400x400.jpg","type":"image\/jpeg"}],"author":"Mauro Felippe","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mauro Felippe"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/#article","isPartOf":{"@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/"},"author":{"name":"Mauro Felippe","@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"headline":"MAURO FELIPPE NA REVISTA ANA MARIA","datePublished":"2020-03-02T13:14:01+00:00","dateModified":"2020-03-02T13:14:38+00:00","mainEntityOfPage":{"@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/"},"wordCount":21,"commentCount":0,"publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"image":{"@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/B0g4KELu_400x400.jpg","keywords":["Mauro Felippe","Na M\u00eddia","palavras t\u00eam vidas","Revista Ana Maria"],"articleSection":["Mat\u00e9rias publicadas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/","url":"http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/","name":"MAURO FELIPPE NA REVISTA ANA MARIA - Mauro Felippe","isPartOf":{"@id":"http:\/\/maurofelippe.com\/br\/#website"},"primaryImageOfPage":{"@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/#primaryimage"},"image":{"@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/B0g4KELu_400x400.jpg","datePublished":"2020-03-02T13:14:01+00:00","dateModified":"2020-03-02T13:14:38+00:00","breadcrumb":{"@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/#primaryimage","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/B0g4KELu_400x400.jpg","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/B0g4KELu_400x400.jpg","width":400,"height":400},{"@type":"BreadcrumbList","@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ana-maria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maurofelippe.com\/"},{"@type":"ListItem","position":2,"name":"MAURO FELIPPE NA REVISTA ANA MARIA"}]},{"@type":"WebSite","@id":"http:\/\/maurofelippe.com\/br\/#website","url":"http:\/\/maurofelippe.com\/br\/","name":"Mauro Felippe","description":"Autor e Escritor","publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/maurofelippe.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb","name":"Mauro Felippe","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","width":164,"height":86,"caption":"Mauro Felippe"},"logo":{"@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png"},"sameAs":["http:\/\/www.maurofelippe.com"],"url":"https:\/\/maurofelippe.com\/br\/author\/lc\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2020\/03\/B0g4KELu_400x400.jpg","jetpack_shortlink":"https:\/\/wp.me\/pavqH1-n7","jetpack-related-posts":[{"id":1297,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-ponto-jovem\/","url_meta":{"origin":1433,"position":0},"title":"Mauro Felippe na Revista Ponto Jovem","author":"Mauro Felippe","date":"08\/10\/2019","format":false,"excerpt":"Revista Ponto Jovem divulgou o livro \"Palavras T\u00eam Vidas\" do autor Mauro Felippe. Para visualizar a mat\u00e9ria na \u00edntegra\u00a0clique aqui.","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/10\/revistas-ponto-jovem.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1472,"url":"https:\/\/maurofelippe.com\/br\/capa-revista-conexao-literatura\/","url_meta":{"origin":1433,"position":1},"title":"CAPA &#8220;REVISTA CONEX\u00c3O LITERATURA&#8221;","author":"Mauro Felippe","date":"03\/11\/2020","format":false,"excerpt":"Mauro Felippe, autor do livro Palavras T\u00eam Vidas, \u00e9 destaque de Capa da nova edi\u00e7\u00e3o da Revista Conex\u00e3o Literatura (Novembro\/n\u00ba 65). Mauro Felippe, autor que vem ganhando notoriedade no meio liter\u00e1rio, \u00e9 destaque da edi\u00e7\u00e3o de Novembro da Revista Conex\u00e3o Literatura. Confira nas p\u00e1ginas da revista um especial sobre o\u2026","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2020\/11\/conexao.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2020\/11\/conexao.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2020\/11\/conexao.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2020\/11\/conexao.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2020\/11\/conexao.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2020\/11\/conexao.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":1482,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-jornal-panorama-2\/","url_meta":{"origin":1433,"position":2},"title":"MAURO FELIPPE NO JORNAL PANORAMA","author":"Mauro Felippe","date":"06\/11\/2020","format":false,"excerpt":"Jornal Panorama divulgou o destaque de capa da Revista Conex\u00e3o Literatura com o autor Mauro Felippe, falando sobre seu \u00faltimo livro \u201cPalavras T\u00eam Vidas\u201d.","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2020\/11\/Untitled-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2020\/11\/Untitled-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2020\/11\/Untitled-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2020\/11\/Untitled-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2020\/11\/Untitled-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2020\/11\/Untitled-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":356,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-conexao-literatura\/","url_meta":{"origin":1433,"position":3},"title":"Mauro Felippe no site Conex\u00e3o Literatura","author":"Mauro Felippe","date":"29\/11\/2018","format":false,"excerpt":"Confira o texto do site Revista Conex\u00e3o Literatura\u00a0 sobre a obra Espectros, de Mauro Felippe: Um olhar sens\u00edvel e cr\u00edtico sobre as fases da vida nos versos talentosos e ricamente ilustrados do escritor catarinense e advogado Mauro Felippe Espectro: conjunto de raios coloridos resultantes da decomposi\u00e7\u00e3o de uma complexa luz;\u2026","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/11\/conexao.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/11\/conexao.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/11\/conexao.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":588,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-revista-styllus\/","url_meta":{"origin":1433,"position":4},"title":"Mauro Felippe na Revista Styllus","author":"Mauro Felippe","date":"07\/12\/2018","format":false,"excerpt":"Confira o texto da Revista Styllus sobre as obras do autor Mauro Felippe. Em 29 de outubro, comemora-se o\u00a0Dia Nacional do Livro. A data surgiu com a funda\u00e7\u00e3o daBiblioteca Nacional do Brasil, em 1810, pela Coroa Portuguesa, no Rio de Janeiro. Nesta \u00e9poca, D. Jo\u00e3o VI trouxe os milhares de\u2026","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Revista-Styllus.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Revista-Styllus.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Revista-Styllus.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":282,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-na-bcc-tv\/","url_meta":{"origin":1433,"position":5},"title":"Mauro Felippe na BCC TV","author":"Mauro Felippe","date":"13\/11\/2018","format":false,"excerpt":"Confira a entrevista de Mauro Felippe no Programa Livros em Revista (BCC TV) \u00a0 \u00a0 \u00a0 \u00a0","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/11\/screenshot-www.youtube.com-2019.01.22-09-30-41.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/11\/screenshot-www.youtube.com-2019.01.22-09-30-41.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/11\/screenshot-www.youtube.com-2019.01.22-09-30-41.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/11\/screenshot-www.youtube.com-2019.01.22-09-30-41.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/1433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/comments?post=1433"}],"version-history":[{"count":1,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/1433\/revisions"}],"predecessor-version":[{"id":1438,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/1433\/revisions\/1438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/media\/1434"}],"wp:attachment":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/media?parent=1433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/categories?post=1433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/tags?post=1433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}