{"id":1999,"date":"2023-09-05T23:28:59","date_gmt":"2023-09-06T02:28:59","guid":{"rendered":"https:\/\/maurofelippe.com\/?p=1999"},"modified":"2023-09-14T20:40:54","modified_gmt":"2023-09-14T23:40:54","slug":"catarse-na-revista-caras","status":"publish","type":"post","link":"https:\/\/maurofelippe.com\/br\/catarse-na-revista-caras\/","title":{"rendered":"Catarse na &#8216;Revista Caras&#8217;"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"720\" height=\"720\" src=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/image.png\" alt=\"\" class=\"wp-image-2000\" srcset=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/image.png 720w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/image-300x300.png 300w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/image-150x150.png 150w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/image-12x12.png 12w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p><strong>Na m\u00eddia, por Lura Editorial:<\/strong> &#8220;Grandes Not\u00edcias! Estamos entusiasmados em compartilhar com voc\u00eas que o nosso livro &#8220;Catarse&#8221;, escrito pelo incr\u00edvel Mauro Felippe e lidamente ilustrado, foi destacado na &#8216;Revista Caras&#8217; portal UOL.<\/p>\n\n\n\n<p><img decoding=\"async\" height=\"16\" width=\"16\" alt=\"?\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t9e\/1\/16\/1f4d6.png\"> Sobre o Livro:<\/p>\n\n\n\n<p>&#8220;Catarse&#8221; \u00e9 uma sintonia entre palavras e imagens, Mauro Felippe nos leva a uma experi\u00eancia \u00fanica com seus textos potentes. Somos suspeitos para falar, ent\u00e3o leia mais no Portal.<\/p>\n\n\n\n<p><img decoding=\"async\" height=\"16\" width=\"16\" alt=\"?\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/td6\/1\/16\/1f4f0.png\"><a><\/a>Na M\u00eddia:<\/p>\n\n\n\n<p>O livro foi caracterizado como um &#8220;must-read&#8221; para todos que procuram poesias e ilustra\u00e7\u00f5es capazes de provocar emo\u00e7\u00f5es profundas. N\u00e3o \u00e9 todo dia que se recebe essa esp\u00e9cie de reconhecimento, e estamos gratos por fazer parte de sua pr\u00f3xima lista de leituras!<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"?\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tb3\/1\/16\/1f517.png\"> Para ler o artigo completo, clica agora neste link: <a href=\"https:\/\/caras.uol.com.br\/vitrine\/autoajuda-poesias-romance-e-mais-10-livros-para-voce-garantir-proxima-leitura.phtml?fbclid=IwAR1JtUHxcGJfY_dpdbakjsyALWW-ug2hg6ouZHLJ-Qo84Kqsw_Or5b1Davw\" rel=\"noreferrer noopener\" target=\"_blank\">https:\/\/caras.uol.com.br\/&#8230;\/autoajuda-poesias-romance-e&#8230;<\/a><\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"?\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t1c\/1\/16\/1f6d2.png\"> Onde Comprar:<\/p>\n\n\n\n<p>Voc\u00ea pode adquirir o seu exemplar de &#8220;Catarse&#8221; agora mesmo de qualquer Estado do Pa\u00eds clicando <a href=\"https:\/\/l.facebook.com\/l.php?u=http%3A%2F%2Flinktr.ee%2Fmaurofelippe%3Ffbclid%3DIwAR1GDQFcZJZASUMQGOURzkSKl7f13ZKtleYOZ-AaywUkpJ613AhXYdsF6wc&amp;h=AT2LBCeuh0OO5VrnFGt2diaTMB6R6aQ5JBmV_emKr3u0HY7ulkKNMZpxTA6eQDaXT-BHhfBtPcEwYUIgmXWiukhHd5xY2DVPZzAal1mtXK0m19r0K4ke5yyYWy8YEnyCrVplAmI6P1Kc1PWAvwte&amp;__tn__=-UK-R&amp;c[0]=AT3FRynDsr_96e2OASNxqYjAkuNLagdFa3TZmrJENbHuztc8IUP-PuKXM7R4QpXSXr7Gso1OeL6nvZSVmmSbURxoBtq6bx2H5_befFKKzHvB63JVkrNX0TpoeoJnrxqFLnsAnAdGawKYiowssVhb1pVcuqHlAOhNbiB04mqCTS01NRXZqyHZBn8-7hy5Rgx1NhL2SVzNcapq\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/linktr.ee\/maurofelippe<\/a> ou em livrarias parceiras como a Amazon. Garanta o seu e embarque nesta viagem liter\u00e1ria!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Ilustra\u00e7\u00f5es e capa: Instagram <strong>@rafaelnobre<\/strong><\/p>\n\n\n\n<p>Contato com o autor e redes sociais:<\/p>\n\n\n\n<p>Facebook:<strong>&nbsp;<a href=\"https:\/\/www.facebook.com\/MauroFelippeAutor\">https:\/\/www.facebook.com\/MauroFelippeAutor<\/a><\/strong><\/p>\n\n\n\n<p>Instagram:&nbsp;<a href=\"http:\/\/www.instagram.com\/maurofelippe\"><strong>www.Instagram.com\/maurofelippe<\/strong><\/a><\/p>\n\n\n\n<p>Youtube:&nbsp;<a href=\"https:\/\/www.youtube.com\/channel\/UC7WCtqQrUUWkiTer1n_kUTQ\"><strong>www.Youtube.com\/maurofelippe<\/strong><\/a><\/p>\n\n\n\n<p>Linktree:&nbsp;<a href=\"https:\/\/linktr.ee\/maurofelippe\"><strong>https:\/\/linktr.ee\/maurofelippe<\/strong><\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na m\u00eddia, por Lura Editorial: &#8220;Grandes Not\u00edcias! Estamos entusiasmados em compartilhar com voc\u00eas que o nosso livro &#8220;Catarse&#8221;, escrito pelo incr\u00edvel Mauro Felippe e lidamente ilustrado, foi destacado na &#8216;Revista Caras&#8217; portal UOL. Sobre o Livro: &#8220;Catarse&#8221; \u00e9 uma sintonia entre palavras e imagens, Mauro Felippe nos leva a uma experi\u00eancia \u00fanica com seus textos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2001,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[176],"tags":[532,63,362,613,528,78,43,612,559,430,41,37,615,80,614,616],"class_list":["post-1999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-materias-publicadas","tag-catarse","tag-divulgacao","tag-lc","tag-leiamais","tag-literaturanacional","tag-livro","tag-livros","tag-livrosrecomendados","tag-luraeditorial","tag-maurofelippe","tag-obras","tag-poesia","tag-poesiailustrada","tag-poeta","tag-revistacaras","tag-uol"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Catarse na &#039;Revista Caras&#039; - Mauro Felippe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maurofelippe.com\/br\/catarse-na-revista-caras\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Catarse na &#039;Revista Caras&#039; - Mauro Felippe\" \/>\n<meta property=\"og:description\" content=\"Na m\u00eddia, por Lura Editorial: &#8220;Grandes Not\u00edcias! Estamos entusiasmados em compartilhar com voc\u00eas que o nosso livro &#8220;Catarse&#8221;, escrito pelo incr\u00edvel Mauro Felippe e lidamente ilustrado, foi destacado na &#8216;Revista Caras&#8217; portal UOL. Sobre o Livro: &#8220;Catarse&#8221; \u00e9 uma sintonia entre palavras e imagens, Mauro Felippe nos leva a uma experi\u00eancia \u00fanica com seus textos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maurofelippe.com\/br\/catarse-na-revista-caras\/\" \/>\n<meta property=\"og:site_name\" content=\"Mauro Felippe\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-06T02:28:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-14T23:40:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/channels4_profile.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mauro Felippe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mauro Felippe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-na-revista-caras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-na-revista-caras\\\/\"},\"author\":{\"name\":\"Mauro Felippe\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"headline\":\"Catarse na &#8216;Revista Caras&#8217;\",\"datePublished\":\"2023-09-06T02:28:59+00:00\",\"dateModified\":\"2023-09-14T23:40:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-na-revista-caras\\\/\"},\"wordCount\":215,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"image\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-na-revista-caras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/channels4_profile.jpg\",\"keywords\":[\"Catarse\",\"divulga\u00e7\u00e3o\",\"LC\",\"LeiaMais\",\"literaturanacional\",\"livro\",\"livros\",\"LivrosRecomendados\",\"luraeditorial\",\"maurofelippe\",\"obras\",\"poesia\",\"PoesiaIlustrada\",\"poeta\",\"RevistaCaras\",\"UOL\"],\"articleSection\":[\"Mat\u00e9rias publicadas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maurofelippe.com\\\/catarse-na-revista-caras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-na-revista-caras\\\/\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-na-revista-caras\\\/\",\"name\":\"Catarse na 'Revista Caras' - Mauro Felippe\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-na-revista-caras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-na-revista-caras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/channels4_profile.jpg\",\"datePublished\":\"2023-09-06T02:28:59+00:00\",\"dateModified\":\"2023-09-14T23:40:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-na-revista-caras\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maurofelippe.com\\\/catarse-na-revista-caras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-na-revista-caras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/channels4_profile.jpg\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/channels4_profile.jpg\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-na-revista-caras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maurofelippe.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catarse na &#8216;Revista Caras&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\",\"url\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/\",\"name\":\"Mauro Felippe\",\"description\":\"Autor e Escritor\",\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\",\"name\":\"Mauro Felippe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"width\":164,\"height\":86,\"caption\":\"Mauro Felippe\"},\"logo\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\"},\"sameAs\":[\"http:\\\/\\\/www.maurofelippe.com\"],\"url\":\"https:\\\/\\\/maurofelippe.com\\\/br\\\/author\\\/lc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Catarse na 'Revista Caras' - Mauro Felippe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maurofelippe.com\/br\/catarse-na-revista-caras\/","og_locale":"pt_BR","og_type":"article","og_title":"Catarse na 'Revista Caras' - Mauro Felippe","og_description":"Na m\u00eddia, por Lura Editorial: &#8220;Grandes Not\u00edcias! Estamos entusiasmados em compartilhar com voc\u00eas que o nosso livro &#8220;Catarse&#8221;, escrito pelo incr\u00edvel Mauro Felippe e lidamente ilustrado, foi destacado na &#8216;Revista Caras&#8217; portal UOL. Sobre o Livro: &#8220;Catarse&#8221; \u00e9 uma sintonia entre palavras e imagens, Mauro Felippe nos leva a uma experi\u00eancia \u00fanica com seus textos [&hellip;]","og_url":"https:\/\/maurofelippe.com\/br\/catarse-na-revista-caras\/","og_site_name":"Mauro Felippe","article_published_time":"2023-09-06T02:28:59+00:00","article_modified_time":"2023-09-14T23:40:54+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/channels4_profile.jpg","type":"image\/jpeg"}],"author":"Mauro Felippe","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mauro Felippe","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maurofelippe.com\/catarse-na-revista-caras\/#article","isPartOf":{"@id":"https:\/\/maurofelippe.com\/catarse-na-revista-caras\/"},"author":{"name":"Mauro Felippe","@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"headline":"Catarse na &#8216;Revista Caras&#8217;","datePublished":"2023-09-06T02:28:59+00:00","dateModified":"2023-09-14T23:40:54+00:00","mainEntityOfPage":{"@id":"https:\/\/maurofelippe.com\/catarse-na-revista-caras\/"},"wordCount":215,"commentCount":0,"publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"image":{"@id":"https:\/\/maurofelippe.com\/catarse-na-revista-caras\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/channels4_profile.jpg","keywords":["Catarse","divulga\u00e7\u00e3o","LC","LeiaMais","literaturanacional","livro","livros","LivrosRecomendados","luraeditorial","maurofelippe","obras","poesia","PoesiaIlustrada","poeta","RevistaCaras","UOL"],"articleSection":["Mat\u00e9rias publicadas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maurofelippe.com\/catarse-na-revista-caras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maurofelippe.com\/catarse-na-revista-caras\/","url":"https:\/\/maurofelippe.com\/catarse-na-revista-caras\/","name":"Catarse na 'Revista Caras' - Mauro Felippe","isPartOf":{"@id":"http:\/\/maurofelippe.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maurofelippe.com\/catarse-na-revista-caras\/#primaryimage"},"image":{"@id":"https:\/\/maurofelippe.com\/catarse-na-revista-caras\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/channels4_profile.jpg","datePublished":"2023-09-06T02:28:59+00:00","dateModified":"2023-09-14T23:40:54+00:00","breadcrumb":{"@id":"https:\/\/maurofelippe.com\/catarse-na-revista-caras\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maurofelippe.com\/catarse-na-revista-caras\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maurofelippe.com\/catarse-na-revista-caras\/#primaryimage","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/channels4_profile.jpg","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/channels4_profile.jpg","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/maurofelippe.com\/catarse-na-revista-caras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maurofelippe.com\/"},{"@type":"ListItem","position":2,"name":"Catarse na &#8216;Revista Caras&#8217;"}]},{"@type":"WebSite","@id":"http:\/\/maurofelippe.com\/br\/#website","url":"http:\/\/maurofelippe.com\/br\/","name":"Mauro Felippe","description":"Autor e Escritor","publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/maurofelippe.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb","name":"Mauro Felippe","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","width":164,"height":86,"caption":"Mauro Felippe"},"logo":{"@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png"},"sameAs":["http:\/\/www.maurofelippe.com"],"url":"https:\/\/maurofelippe.com\/br\/author\/lc\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/channels4_profile.jpg","jetpack_shortlink":"https:\/\/wp.me\/pavqH1-wf","jetpack-related-posts":[{"id":2046,"url":"https:\/\/maurofelippe.com\/br\/catarse-no-portal-meia-92\/","url_meta":{"origin":1999,"position":0},"title":"CATARSE, no Portal Meia 92","author":"Mauro Felippe","date":"11\/09\/2023","format":false,"excerpt":"CATARSE, no @portalmeia92, de S\u00e3o Paulo-SP. Belo portal de entretenimento. Entrevista completa no pr\u00f3prio Portal, que desde j\u00e1 o agrade\u00e7o! Acesse a entrevista completa clicando diretamente aqui: https:\/\/meia92.com.br\/...\/em-entrevista-escritor-mauro...\/ Obrigado! \u00a0Livros e livrarias aqui:\u00a0http:\/\/linktr.ee\/maurofelippe Contato com o autor e redes sociais: Facebook:\u00a0https:\/\/www.facebook.com\/MauroFelippeAutor Instagram:\u00a0www.Instagram.com\/maurofelippe Youtube:\u00a0www.Youtube.com\/maurofelippe Linktree:\u00a0https:\/\/linktr.ee\/maurofelippe","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-6.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2027,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-espirito-santo-noticias\/","url_meta":{"origin":1999,"position":1},"title":"MAURO FELIPPE NO Esp\u00edrito Santo Not\u00edcias&#8217;","author":"Mauro Felippe","date":"09\/09\/2023","format":false,"excerpt":"Nova mat\u00e9ria sobre o meu novo livro CATARSE, pela Lura Editorial. Obrigado, 'Esp\u00edrito Santo Not\u00edcias', pelo release no Portal\/Jornal, via Sudeste do Pa\u00eds. Mat\u00e9ria completa clica aqui: https:\/\/www.espiritosantonoticias.com.br\/o-caos-da...\/... Obrigado! \u00a0Livros e livrarias aqui:\u00a0http:\/\/linktr.ee\/maurofelippe Contato com o autor e redes sociais: Facebook:\u00a0https:\/\/www.facebook.com\/MauroFelippeAutor Instagram:\u00a0www.Instagram.com\/maurofelippe Youtube:\u00a0www.Youtube.com\/maurofelippe Linktree:\u00a0https:\/\/linktr.ee\/maurofelippe . #maurofelippe#luraeditorial#espiritosanto#espiritosantonoticias#literatura#instalivros#bienaldolivro#poesia#poes\u00eda#catarse#livros#lan\u00e7amento","rel":"","context":"Em &quot;Mat\u00e9rias publicadas&quot;","block_context":{"text":"Mat\u00e9rias publicadas","link":"https:\/\/maurofelippe.com\/br\/category\/materias-publicadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/image-8.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/image-8.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/image-8.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1575,"url":"https:\/\/maurofelippe.com\/br\/catarse-trailer-lancamento-novo-livro-mauro-felippe\/","url_meta":{"origin":1999,"position":2},"title":"CATARSE &#8211; Trailer Lan\u00e7amento Novo Livro Mauro Felippe","author":"Mauro Felippe","date":"24\/03\/2023","format":false,"excerpt":"?Vem a\u00ed: CATARSE. Contagem regressiva para lan\u00e7amento simult\u00e2neo nas livrarias de todo Pa\u00eds. Novo Livro de Mauro Felippe. Lan\u00e7amento 2023 \u00a0 \u00a0 http:\/\/www.maurofelippe.com https:\/\/www.instagram.com\/maurofelippe https:\/\/www.facebook.com\/MauroFelippe... \u00a0 #maurofelippe #curtapoesia #poesia #literatura #novo #maurofelippe #Catarse #cultura #livros #books #livro #curtapoesia #poes\u00eda #poesia #psico #arte #capadura #mentalidade #instapoesia #instalivros #literatura #bookstagram #poesiacontemporanea #espalhepoesia\u2026","rel":"","context":"Em &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/br\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/03\/zzz2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/03\/zzz2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/03\/zzz2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1622,"url":"https:\/\/maurofelippe.com\/br\/catarse-de-mauro-felippe-video-clipe-lancamento-nacional\/","url_meta":{"origin":1999,"position":3},"title":"&#8220;CATARSE&#8221; Novo Livro de Mauro Felippe &#8211; Video Clipe Lan\u00e7amento Nacional","author":"Mauro Felippe","date":"25\/07\/2023","format":false,"excerpt":"\u00a0 VIDEO CLIPE LAN\u00c7AMENTO NACIONAL: \"CATARSE\" Novo livro de Mauro Felippe. Compre on-line: https:\/\/linktr.ee\/maurofelippe Dispon\u00edvel nas melhores livrarias do Pa\u00eds. Confira abaixo o video clipe no formato Vertical para Smart Phones e tamb\u00e9m no formato Wide Screen para Monitores e Televisores. *Formato Vertical (ideal para Smart Phones). \u00a0 *Formato Wide\u2026","rel":"","context":"Em &quot;Reflex\u00e3o e Cr\u00f4nicas&quot;","block_context":{"text":"Reflex\u00e3o e Cr\u00f4nicas","link":"https:\/\/maurofelippe.com\/br\/category\/reflexao-e-cronicas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/07\/Teaser-Catrase-fullHD-v4.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/07\/Teaser-Catrase-fullHD-v4.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/07\/Teaser-Catrase-fullHD-v4.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/07\/Teaser-Catrase-fullHD-v4.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/07\/Teaser-Catrase-fullHD-v4.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/07\/Teaser-Catrase-fullHD-v4.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":2060,"url":"https:\/\/maurofelippe.com\/br\/catarse-na-coluna-do-eraldo-luiz-da-silva\/","url_meta":{"origin":1999,"position":4},"title":"Catarse na coluna do eraldo luiz da silva","author":"Mauro Felippe","date":"15\/09\/2023","format":false,"excerpt":"\u00a0Livros e livrarias aqui:\u00a0http:\/\/linktr.ee\/maurofelippe Contato com o autor e redes sociais: Facebook:\u00a0https:\/\/www.facebook.com\/MauroFelippeAutor Instagram:\u00a0www.Instagram.com\/maurofelippe Youtube:\u00a0www.Youtube.com\/maurofelippe Linktree:\u00a0https:\/\/linktr.ee\/maurofelippe","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-10.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-10.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-10.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":2037,"url":"https:\/\/maurofelippe.com\/br\/catarse-no-jornal-correio-popular\/","url_meta":{"origin":1999,"position":5},"title":"CATARSE, no Jornal Correio Popular","author":"Mauro Felippe","date":"10\/09\/2023","format":false,"excerpt":"CATARSE, no Jornal Correio Popular, de Campinas-SP, na Coluna 'Societ\u00e1', do Jornalista Almir Reis (cr\u00e9ditos de Amor Reis). #saopaulo#campinas#campinassp Mat\u00e9ria completa j\u00e1 postada no meu Site e demais redes, e no pr\u00f3prio Jornal, que desde j\u00e1 o agrade\u00e7o! \u00a0Livros e livrarias aqui:\u00a0http:\/\/linktr.ee\/maurofelippe Contato com o autor e redes sociais: Facebook:\u00a0https:\/\/www.facebook.com\/MauroFelippeAutor\u2026","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-2.png?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/1999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/comments?post=1999"}],"version-history":[{"count":2,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/1999\/revisions"}],"predecessor-version":[{"id":2084,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/1999\/revisions\/2084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/media\/2001"}],"wp:attachment":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/media?parent=1999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/categories?post=1999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/tags?post=1999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}