{"id":554,"date":"2018-12-07T16:55:51","date_gmt":"2018-12-07T18:55:51","guid":{"rendered":"https:\/\/maurofelippe.com\/?p=554"},"modified":"2019-01-22T09:14:49","modified_gmt":"2019-01-22T11:14:49","slug":"mauro-felippe-no-site-lopes-acioli","status":"publish","type":"post","link":"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/","title":{"rendered":"Mauro Felippe no site Lopes Acioli"},"content":{"rendered":"<p>Confira o texto do<a href=\"http:\/\/www.lopeseaciolieditora.com.br\/index.php?page=Global&amp;alias=reflexos-de-sensibilidade-em-luz-e-poesia\"> site Lopes Acioli<\/a> sobre as obras do autor Mauro Felippe.<\/p>\n<div class=\"panel-body\">\n<blockquote><p>Com textos de profundidade subjetiva e de inspira\u00e7\u00f5es ora psicol\u00f3gicas, ora filos\u00f3ficas, o autor permeia pelo passar dos anos e os reflete no livro Espectros. O poeta catarinense Mauro Felippe partilha da ideia de que cada \u00e9poca da vida \u00e9 multiplicada pelas sucessivas reflex\u00f5es das que lhe seguem, e, por isso, para a crian\u00e7a o tempo \u00e9 t\u00e3o longo e, em contrapartida, a fase da velhice parece t\u00e3o curta.<\/p>\n<p>Espectros \u00e9 prefaciado pelo psic\u00f3logo, professor e escritor Adroaldo Bittencourt e pela poetisa e educadora Anna Zin Pilotto \u2013 ambos grandes especialistas em suas respectivas \u00e1reas \u2013, que antecipam para o leitor: versos marcantes e uma grande aventura po\u00e9tica est\u00e3o por vir. Mauro Felippe criou a obra a partir de ensaios provenientes de per\u00edodos ociosos de paz interior que resultaram em tal constru\u00e7\u00e3o, profunda e desprovida de princ\u00edpio, meio e fim. Ou seja, cada pe\u00e7a vale por si mesma, sem estar ligada necessariamente \u00e0 outra numa sequ\u00eancia, sendo cada p\u00e1gina o seu pr\u00f3prio come\u00e7o e final de acordo com os crit\u00e9rios do pr\u00f3prio leitor.<\/p><\/blockquote>\n<\/div>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-555\" src=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/200501cc1e54fba3e365124daf4a9e2f.jpg\" alt=\"\" width=\"1280\" height=\"768\" srcset=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/200501cc1e54fba3e365124daf4a9e2f.jpg 1280w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/200501cc1e54fba3e365124daf4a9e2f-300x180.jpg 300w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/200501cc1e54fba3e365124daf4a9e2f-768x461.jpg 768w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/200501cc1e54fba3e365124daf4a9e2f-1024x614.jpg 1024w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confira o texto do site Lopes Acioli sobre as obras do autor Mauro Felippe. Com textos de profundidade subjetiva e de inspira\u00e7\u00f5es ora psicol\u00f3gicas, ora filos\u00f3ficas, o autor permeia pelo passar dos anos e os reflete no livro Espectros. O poeta catarinense Mauro Felippe partilha da ideia de que cada \u00e9poca da vida \u00e9 multiplicada [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":520,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,176],"tags":[63,13,83,81,79,38,78,43,94,33,82,41,56,37,80,92,54],"class_list":["post-554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-imprensa","category-materias-publicadas","tag-divulgacao","tag-espectros","tag-humanos","tag-imprensa","tag-leitura","tag-literatura","tag-livro","tag-livros","tag-lopes-acioli","tag-mauro-felippe","tag-nove","tag-obras","tag-ocio","tag-poesia","tag-poeta","tag-portal","tag-site"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mauro Felippe no site Lopes Acioli - Mauro Felippe<\/title>\n<meta name=\"description\" content=\"Confira o texto do site Lopes Acioli sobre as obras do autor Mauro Felippe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mauro Felippe no site Lopes Acioli - Mauro Felippe\" \/>\n<meta property=\"og:description\" content=\"Confira o texto do site Lopes Acioli sobre as obras do autor Mauro Felippe.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/\" \/>\n<meta property=\"og:site_name\" content=\"Mauro Felippe\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-07T18:55:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-22T11:14:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Lopes-e-Acioli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"352\" \/>\n\t<meta property=\"og:image:height\" content=\"352\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mauro Felippe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mauro Felippe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-no-site-lopes-acioli\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-no-site-lopes-acioli\\\/\"},\"author\":{\"name\":\"Mauro Felippe\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"headline\":\"Mauro Felippe no site Lopes Acioli\",\"datePublished\":\"2018-12-07T18:55:51+00:00\",\"dateModified\":\"2019-01-22T11:14:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-no-site-lopes-acioli\\\/\"},\"wordCount\":207,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"image\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-no-site-lopes-acioli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Lopes-e-Acioli.jpg\",\"keywords\":[\"divulga\u00e7\u00e3o\",\"espectros\",\"Humanos\",\"imprensa\",\"leitura\",\"literatura\",\"livro\",\"livros\",\"Lopes Acioli\",\"Mauro Felippe\",\"Nove\",\"obras\",\"\u00d3cio\",\"poesia\",\"poeta\",\"portal\",\"site\"],\"articleSection\":[\"Imprensa\",\"Mat\u00e9rias publicadas\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-no-site-lopes-acioli\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-no-site-lopes-acioli\\\/\",\"url\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-no-site-lopes-acioli\\\/\",\"name\":\"Mauro Felippe no site Lopes Acioli - Mauro Felippe\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-no-site-lopes-acioli\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-no-site-lopes-acioli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Lopes-e-Acioli.jpg\",\"datePublished\":\"2018-12-07T18:55:51+00:00\",\"dateModified\":\"2019-01-22T11:14:49+00:00\",\"description\":\"Confira o texto do site Lopes Acioli sobre as obras do autor Mauro Felippe.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-no-site-lopes-acioli\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-no-site-lopes-acioli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-no-site-lopes-acioli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Lopes-e-Acioli.jpg\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Lopes-e-Acioli.jpg\",\"width\":352,\"height\":352},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/mauro-felippe-no-site-lopes-acioli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maurofelippe.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mauro Felippe no site Lopes Acioli\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\",\"url\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/\",\"name\":\"Mauro Felippe\",\"description\":\"Autor e Escritor\",\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\",\"name\":\"Mauro Felippe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"width\":164,\"height\":86,\"caption\":\"Mauro Felippe\"},\"logo\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\"},\"sameAs\":[\"http:\\\/\\\/www.maurofelippe.com\"],\"url\":\"https:\\\/\\\/maurofelippe.com\\\/br\\\/author\\\/lc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mauro Felippe no site Lopes Acioli - Mauro Felippe","description":"Confira o texto do site Lopes Acioli sobre as obras do autor Mauro Felippe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/","og_locale":"pt_BR","og_type":"article","og_title":"Mauro Felippe no site Lopes Acioli - Mauro Felippe","og_description":"Confira o texto do site Lopes Acioli sobre as obras do autor Mauro Felippe.","og_url":"http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/","og_site_name":"Mauro Felippe","article_published_time":"2018-12-07T18:55:51+00:00","article_modified_time":"2019-01-22T11:14:49+00:00","og_image":[{"width":352,"height":352,"url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Lopes-e-Acioli.jpg","type":"image\/jpeg"}],"author":"Mauro Felippe","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mauro Felippe","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/#article","isPartOf":{"@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/"},"author":{"name":"Mauro Felippe","@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"headline":"Mauro Felippe no site Lopes Acioli","datePublished":"2018-12-07T18:55:51+00:00","dateModified":"2019-01-22T11:14:49+00:00","mainEntityOfPage":{"@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/"},"wordCount":207,"commentCount":0,"publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"image":{"@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Lopes-e-Acioli.jpg","keywords":["divulga\u00e7\u00e3o","espectros","Humanos","imprensa","leitura","literatura","livro","livros","Lopes Acioli","Mauro Felippe","Nove","obras","\u00d3cio","poesia","poeta","portal","site"],"articleSection":["Imprensa","Mat\u00e9rias publicadas"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/","url":"http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/","name":"Mauro Felippe no site Lopes Acioli - Mauro Felippe","isPartOf":{"@id":"http:\/\/maurofelippe.com\/br\/#website"},"primaryImageOfPage":{"@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/#primaryimage"},"image":{"@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Lopes-e-Acioli.jpg","datePublished":"2018-12-07T18:55:51+00:00","dateModified":"2019-01-22T11:14:49+00:00","description":"Confira o texto do site Lopes Acioli sobre as obras do autor Mauro Felippe.","breadcrumb":{"@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/#primaryimage","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Lopes-e-Acioli.jpg","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Lopes-e-Acioli.jpg","width":352,"height":352},{"@type":"BreadcrumbList","@id":"http:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-lopes-acioli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maurofelippe.com\/"},{"@type":"ListItem","position":2,"name":"Mauro Felippe no site Lopes Acioli"}]},{"@type":"WebSite","@id":"http:\/\/maurofelippe.com\/br\/#website","url":"http:\/\/maurofelippe.com\/br\/","name":"Mauro Felippe","description":"Autor e Escritor","publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/maurofelippe.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb","name":"Mauro Felippe","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","width":164,"height":86,"caption":"Mauro Felippe"},"logo":{"@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png"},"sameAs":["http:\/\/www.maurofelippe.com"],"url":"https:\/\/maurofelippe.com\/br\/author\/lc\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Lopes-e-Acioli.jpg","jetpack_shortlink":"https:\/\/wp.me\/pavqH1-8W","jetpack-related-posts":[{"id":356,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-conexao-literatura\/","url_meta":{"origin":554,"position":0},"title":"Mauro Felippe no site Conex\u00e3o Literatura","author":"Mauro Felippe","date":"29\/11\/2018","format":false,"excerpt":"Confira o texto do site Revista Conex\u00e3o Literatura\u00a0 sobre a obra Espectros, de Mauro Felippe: Um olhar sens\u00edvel e cr\u00edtico sobre as fases da vida nos versos talentosos e ricamente ilustrados do escritor catarinense e advogado Mauro Felippe Espectro: conjunto de raios coloridos resultantes da decomposi\u00e7\u00e3o de uma complexa luz;\u2026","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/11\/conexao.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/11\/conexao.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/11\/conexao.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":558,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-site-eu-leio-brasil\/","url_meta":{"origin":554,"position":1},"title":"Mauro Felippe no site Eu Leio Brasil","author":"Mauro Felippe","date":"07\/12\/2018","format":false,"excerpt":"Confira o texto do site Eu Leio Brasil sobre a obra Espectros, de Mauro Felippe. Um olhar sens\u00edvel e cr\u00edtico sobre as fases da vida nos versos talentosos e ricamente ilustrados do escritor catarinense e advogado Mauro Felippe Espectro: conjunto de raios coloridos resultantes da decomposi\u00e7\u00e3o de uma complexa luz;\u2026","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Eu-leio-brasil.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Eu-leio-brasil.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Eu-leio-brasil.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":547,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-portal-segs\/","url_meta":{"origin":554,"position":2},"title":"Mauro Felippe no Portal SEGS","author":"Mauro Felippe","date":"07\/12\/2018","format":false,"excerpt":"Confira o texto do portal SEGS sobre as obras do autor Mauro Felippe. Um olhar sens\u00edvel e cr\u00edtico sobre as fases da vida nos versos talentosos e ricamente ilustrados do escritor catarinense e advogado Mauro Felippe. Espectro: conjunto de raios coloridos resultantes da decomposi\u00e7\u00e3o de uma complexa luz; a decomposi\u00e7\u00e3o\u2026","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/1db9fd7368c5c039c0fd4c8835e5f8e9.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/1db9fd7368c5c039c0fd4c8835e5f8e9.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/1db9fd7368c5c039c0fd4c8835e5f8e9.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/1db9fd7368c5c039c0fd4c8835e5f8e9.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/1db9fd7368c5c039c0fd4c8835e5f8e9.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":346,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-tomo-literario\/","url_meta":{"origin":554,"position":3},"title":"Mauro Felippe no Tomo Liter\u00e1rio","author":"Mauro Felippe","date":"29\/11\/2018","format":false,"excerpt":"Confira o texto do blog Tomo Liter\u00e1rio sobre a obra Espectros, de Mauro Felippe: Um olhar sens\u00edvel e cr\u00edtico sobre as fases da vida nos versos talentosos e ricamente ilustrados do escritor catarinense e advogado Mauro Felippe Espectro: conjunto de raios coloridos resultantes da decomposi\u00e7\u00e3o de uma complexa luz; a\u2026","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/11\/Tomo-Liter%C3%A1rio-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/11\/Tomo-Liter%C3%A1rio-logo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/11\/Tomo-Liter%C3%A1rio-logo.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":544,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-blog-uma-leitora\/","url_meta":{"origin":554,"position":4},"title":"Mauro Felippe no blog Uma Leitora","author":"Mauro Felippe","date":"07\/12\/2018","format":false,"excerpt":"Confira o texto do blog Uma Leitora sobre a obra Espectros, de Mauro Felippe. Com textos de profundidade subjetiva e de inspira\u00e7\u00f5es ora psicol\u00f3gicas, ora filos\u00f3ficas, o autor permeia pelo passar dos anos e os reflete no livro Espectros. O poeta catarinense Mauro Felippe partilha da ideia de que cada\u2026","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Uma-leitora.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Uma-leitora.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Uma-leitora.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":596,"url":"https:\/\/maurofelippe.com\/br\/mauro-felippe-no-jornal-dia-a-dia-2\/","url_meta":{"origin":554,"position":5},"title":"Mauro Felippe no Jornal Dia a Dia","author":"Mauro Felippe","date":"07\/12\/2018","format":false,"excerpt":"Confira o texto do Jornal Dia a Dia sobre as obras do autor Mauro Felippe. Com textos de profundidade subjetiva e de inspira\u00e7\u00f5es ora psicol\u00f3gicas, ora filos\u00f3ficas, o autor permeia pelo passar dos anos e os reflete no livro\u00a0Espectros. O poeta catarinense Mauro Felippe partilha da ideia de que cada\u2026","rel":"","context":"Em &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/br\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Jornal-Dia-a-dia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Jornal-Dia-a-dia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2018\/12\/Jornal-Dia-a-dia.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/comments?post=554"}],"version-history":[{"count":4,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/554\/revisions"}],"predecessor-version":[{"id":884,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/posts\/554\/revisions\/884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/media\/520"}],"wp:attachment":[{"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/media?parent=554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/categories?post=554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maurofelippe.com\/br\/wp-json\/wp\/v2\/tags?post=554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}