{"id":1041,"date":"2019-04-16T10:16:33","date_gmt":"2019-04-16T13:16:33","guid":{"rendered":"https:\/\/maurofelippe.com\/?p=1041"},"modified":"2019-04-16T10:16:33","modified_gmt":"2019-04-16T13:16:33","slug":"os-significados-da-pascoa","status":"publish","type":"post","link":"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/","title":{"rendered":"Os Significados da P\u00e1scoa"},"content":{"rendered":"<p style=\"text-align: center;\" align=\"center\"><span style=\"color: #000000;\"><em><span style=\"font-size: 11.0pt; font-family: 'Arial','sans-serif';\">Desde crian\u00e7a (faz tempo), ou\u00e7o dizer: \u201cN\u00e3o se come<\/span><\/em><span style=\"font-size: 11.0pt; font-family: 'Arial','sans-serif';\"><br \/>\n<em><span style=\"font-family: 'Arial','sans-serif';\">carne na Sexta-Feira Santa porque \u00e9 Sexta-Feira Santa.\u201d<\/span><\/em><br \/>\n<em><span style=\"font-family: 'Arial','sans-serif';\">\u00c9 uma das provas como a cultura, a tradi\u00e7\u00e3o, os<\/span><\/em><br \/>\n<em><span style=\"font-family: 'Arial','sans-serif';\">dogmas, contagiam-nos a ponto de considerarmos, com<\/span><\/em><br \/>\n<em><span style=\"font-family: 'Arial','sans-serif';\">efeito cogente, uma norma religiosa, psicologicamente<\/span><\/em><br \/>\n<em><span style=\"font-family: 'Arial','sans-serif';\">imperdo\u00e1vel em caso de contrari\u00e1-la.<\/span><\/em><br \/>\n<em><span style=\"font-family: 'Arial','sans-serif';\">&#8230; E o Z\u00e9 falou aos muitos amigos que o<\/span><\/em><br \/>\n<em><span style=\"font-family: 'Arial','sans-serif';\">acompanhavam, no Dia Santo: -\u201cEnt\u00e3o vamos matar uma<\/span><\/em><br \/>\n<em><span style=\"font-family: 'Arial','sans-serif';\">galinha e um peixe!! Pelo menos o assassinato deles \u00e9<\/span><\/em><br \/>\n<em><span style=\"font-family: 'Arial','sans-serif';\">isento de pecado e culpa, porque hoje \u00e9 Sexta-Feira Santa.<\/span><\/em><br \/>\n<em><span style=\"font-family: 'Arial','sans-serif';\">Deixa comigo que eu mesmo os mato.\u201d<\/span><\/em><br \/>\n<em><span style=\"font-family: 'Arial','sans-serif';\">No dia seguinte, S\u00e1bado, Z\u00e9 e os demais amigos que<\/span><\/em><br \/>\n<em><span style=\"font-family: 'Arial','sans-serif';\">comeram os bichinhos de \u201ccarne diferente\u201d colocaram-se<\/span><\/em><br \/>\n<em><span style=\"font-family: 'Arial','sans-serif';\">ao lamento, \u00e0s l\u00e1grimas, ao arrependimento, por terem<\/span><\/em><br \/>\n<em><span style=\"font-family: 'Arial','sans-serif';\">comido, sem perceber, em um dia santo, dois filhinhos de<\/span><\/em><br \/>\n<em><span style=\"font-family: 'Arial','sans-serif';\">Deus&#8230;<\/span><\/em><\/span><\/span><\/p>\n<p style=\"text-align: center;\" align=\"center\"><span style=\"font-size: 11pt; font-family: Arial, sans-serif; color: #000000;\">(Dia Santo, com carne, n\u00e3o pode! &#8211; Mauro Felippe, extra\u00eddo do livro Espectros)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 11pt; font-family: Arial, sans-serif; color: #000000;\">\u00a0A P\u00e1scoa \u00e9 uma das datas comemorativas mais importantes entre as culturas ocidentais. A origem desta comemora\u00e7\u00e3o remonta muitos S\u00e9culos atr\u00e1s. O termo \u201cP\u00e1scoa\u201d tem uma origem religiosa que vem do hebraico\u00a0<em><span style=\"font-family: 'Arial','sans-serif';\">pesah<\/span><\/em>, que significa passagem.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 11pt; font-family: Arial, sans-serif; color: #000000;\">J\u00e1 na Gr\u00e9cia Antiga, este termo tamb\u00e9m \u00e9 encontrado como\u00a0<em><span style=\"font-family: 'Arial','sans-serif';\">Paska<\/span><\/em>.\u00a0A palavra tem sua origem ligada \u00e0 religiosidade e significa &#8220;alimento&#8221;, ou seja, o fim do jejum da Quaresma.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 11pt; font-family: Arial, sans-serif; color: #000000;\">Antigamente, nesta data, os antigos povos pag\u00e3os (Celtas, Fen\u00edcios, Eg\u00edpcios, etc.) festejavam a chegada da primavera e o fim do inverno. Naquele contexto, essa celebra\u00e7\u00e3o simbolizava a sobreviv\u00eancia da esp\u00e9cie humana.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 11pt; font-family: Arial, sans-serif; color: #000000;\">Essa Festa era celebrada, principalmente, na regi\u00e3o do Mediterr\u00e2neo, durante o M\u00eas de Mar\u00e7o. Geralmente, a comemora\u00e7\u00e3o era realizada na primeira lua cheia da \u00e9poca das flores. Entre os povos da antiguidade, o fim do inverno e o come\u00e7o da primavera era de extrema import\u00e2ncia, pois estava ligado a maiores chances de sobreviv\u00eancia em fun\u00e7\u00e3o do rigoroso inverno que castigava a Europa, dificultando a produ\u00e7\u00e3o de alimentos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><span style=\"font-size: 11.0pt; font-family: 'Arial','sans-serif';\">P\u00e1scoa na liturgia Crist\u00e3<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 11pt; font-family: Arial, sans-serif; color: #000000;\">A comemora\u00e7\u00e3o que relembra a crucifica\u00e7\u00e3o e celebra a ressurrei\u00e7\u00e3o de Jesus Cristo, celebra\u00e7\u00e3o da P\u00e1scoa, acontece durante a Semana Santa, per\u00edodo do Cristianismo que tem in\u00edcio no Domingo de Ramos, dia que marca a entrada de Cristo em Jerusal\u00e9m.\u00a0Ela \u00e9 considerada uma das mais importantes datas comemorativas que simboliza uma nova vida, nova era, esperan\u00e7a. J\u00e1 a Quaresma representa os 40 dias que antecedem a P\u00e1scoa, e corresponde a uma forma de penit\u00eancia realizada pelos fi\u00e9is crist\u00e3os. \u00c9 comum as pessoas fazerem promessas durante esse per\u00edodo e absterem-se de carnes vermelhas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: 11pt; font-family: Arial, sans-serif;\">&#8211;<\/span><span style=\"font-size: 11.0pt; font-family: 'Arial','sans-serif';\">Mas, por que algumas pessoas n\u00e3o comem carne vermelha na Sexta-Feira Santa? Conhecido tamb\u00e9m como Sexta da Paix\u00e3o,\u00a0\u00e9 um dia reservado para a pr\u00e1tica da abstin\u00eancia, onde os cat\u00f3licos reservam para o reconhecimento do sacrif\u00edcio de Jesus Cristo. Segundo as escrituras da B\u00edblia, Jesus viveu e morreu para salvar todas as pessoas de seus pecados.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 11pt; font-family: Arial, sans-serif; color: #000000;\">Por isso, a Igreja Cat\u00f3lica recomenda aos fi\u00e9is que reconhe\u00e7am o sacrif\u00edcio que foi a vida daquele que d\u00e1 nome ao cristianismo. A abstin\u00eancia de carne vermelha, presente no card\u00e1pio da maioria das pessoas, e o jejum, s\u00e3o algumas das recomenda\u00e7\u00f5es. Mas, ao contr\u00e1rio do que muitos pensam, a Igreja recomenda que todas as sextas-feiras do ano sejam reservadas \u00e0 abstin\u00eancia de carne e n\u00e3o apenas \u00e0quela considerada Santa. J\u00e1 a\u00a0tradi\u00e7\u00e3o de comer peixes na Sexta-Feira Santa \u00e9, portanto, apenas uma cultura cultivada pelas pessoas h\u00e1 muitos anos, com base no\u00a0C\u00f3digo de Direito Can\u00f4nico, o Livro que rege as regras da Igreja Cat\u00f3lica.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 11pt; font-family: Arial, sans-serif; color: #000000;\">\u00c9 v\u00e1lido frisar tamb\u00e9m, que, a data de comemora\u00e7\u00e3o varia dos dias 22 de Mar\u00e7o (data do Equin\u00f3cio) a 25 de Abril. A semana que antecede o Domingo de P\u00e1scoa \u00e9 denominada de \u201cSemana Santa<strong><span style=\"font-family: 'Arial','sans-serif';\">\u201d. <\/span><\/strong>Essa varia\u00e7\u00e3o de datas acontece porque a\u00a0P\u00e1scoa\u00a0n\u00e3o\u00a0cai no mesmo dia\u00a0todo ano, pois\u00a0\u00e9 comemorada no primeiro domingo de lua cheia ap\u00f3s a entrada da primavera no Hemisf\u00e9rio Norte (no Hemisf\u00e9rio Sul \u00e9 in\u00edcio de outono).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong><span style=\"font-size: 11.0pt; font-family: 'Arial','sans-serif';\">O s\u00edmbolo do Coelho e dos ovos<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: 11pt; font-family: Arial, sans-serif;\">&#8211; <\/span><span style=\"font-size: 11.0pt; font-family: 'Arial','sans-serif';\">Mas, o que a reprodu\u00e7\u00e3o tem a ver com os significados religiosos da P\u00e1scoa? Tanto no significado Crist\u00e3o quanto no de outros segmentos, esta data relaciona-se com a esperan\u00e7a de uma vida nova. J\u00e1 os ovos de P\u00e1scoa tamb\u00e9m est\u00e3o neste contexto da fecundidade e da vida.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 11pt; font-family: Arial, sans-serif; color: #000000;\">No ponto de vista pag\u00e3o, derivado do ingl\u00eas,\u00a0<em><span style=\"font-family: 'Arial','sans-serif';\">Easter,<\/span><\/em>\u00a0que significa P\u00e1scoa, est\u00e1 intimamente ligado aos cultos da deusa da fertilidade da mitologia n\u00f3rdica e germ\u00e2nica. Acredita-se que o coelho e os ovos coloridos surgiram da\u00ed, uma vez que s\u00e3o s\u00edmbolos de renova\u00e7\u00e3o da deusa e nascimento em diversas culturas. Ent\u00e3o, desde a antiguidade, ele, o coelho, est\u00e1 associado \u00e0 troca de ovos realizada por muitos povos, como s\u00edmbolo de sorte.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Desde crian\u00e7a (faz tempo), ou\u00e7o dizer: \u201cN\u00e3o se come carne na Sexta-Feira Santa porque \u00e9 Sexta-Feira Santa.\u201d \u00c9 uma das provas como a cultura, a tradi\u00e7\u00e3o, os dogmas, contagiam-nos a ponto de considerarmos, com efeito cogente, uma norma religiosa, psicologicamente imperdo\u00e1vel em caso de contrari\u00e1-la. &#8230; E o Z\u00e9 falou aos muitos amigos que o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,31],"tags":[309,308,303,310,302,306,78,33,304,301,37,307,305],"class_list":["post-1041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-reflexao-e-cronicas","tag-abril","tag-biblia","tag-coelho","tag-crista","tag-igreja-catolica","tag-jesus-cristo","tag-livro","tag-mauro-felippe","tag-ovos-de-pascoa","tag-pascoa","tag-poesia","tag-ressurreicao","tag-sexta-feira-santa"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Os Significados da P\u00e1scoa - Mauro Felippe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Os Significados da P\u00e1scoa - Mauro Felippe\" \/>\n<meta property=\"og:description\" content=\"Desde crian\u00e7a (faz tempo), ou\u00e7o dizer: \u201cN\u00e3o se come carne na Sexta-Feira Santa porque \u00e9 Sexta-Feira Santa.\u201d \u00c9 uma das provas como a cultura, a tradi\u00e7\u00e3o, os dogmas, contagiam-nos a ponto de considerarmos, com efeito cogente, uma norma religiosa, psicologicamente imperdo\u00e1vel em caso de contrari\u00e1-la. &#8230; E o Z\u00e9 falou aos muitos amigos que o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/\" \/>\n<meta property=\"og:site_name\" content=\"Mauro Felippe\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-16T13:16:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Pa\u0301scoa-1024x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mauro Felippe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mauro Felippe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/os-significados-da-pascoa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/os-significados-da-pascoa\\\/\"},\"author\":{\"name\":\"Mauro Felippe\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"headline\":\"Os Significados da P\u00e1scoa\",\"datePublished\":\"2019-04-16T13:16:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/os-significados-da-pascoa\\\/\"},\"wordCount\":850,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"image\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/os-significados-da-pascoa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Pa\u0301scoa.png\",\"keywords\":[\"abril\",\"b\u00edblia\",\"Coelho\",\"crist\u00e3\",\"Igreja Cat\u00f3lica\",\"Jesus Cristo\",\"livro\",\"Mauro Felippe\",\"Ovos de P\u00e1scoa\",\"P\u00e1scoa\",\"poesia\",\"ressurrei\u00e7\u00e3o\",\"Sexta feira Santa\"],\"articleSection\":[\"Artigos\",\"Reflex\u00e3o e Cr\u00f4nicas\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maurofelippe.com\\\/en\\\/os-significados-da-pascoa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/os-significados-da-pascoa\\\/\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/os-significados-da-pascoa\\\/\",\"name\":\"Os Significados da P\u00e1scoa - Mauro Felippe\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/os-significados-da-pascoa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/os-significados-da-pascoa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Pa\u0301scoa.png\",\"datePublished\":\"2019-04-16T13:16:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/os-significados-da-pascoa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maurofelippe.com\\\/en\\\/os-significados-da-pascoa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/os-significados-da-pascoa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Pa\u0301scoa.png\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Pa\u0301scoa.png\",\"width\":3333,\"height\":3333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/os-significados-da-pascoa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maurofelippe.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Os Significados da P\u00e1scoa\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\",\"url\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/\",\"name\":\"Mauro Felippe\",\"description\":\"Autor e Escritor\",\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\",\"name\":\"Mauro Felippe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"width\":164,\"height\":86,\"caption\":\"Mauro Felippe\"},\"logo\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\"},\"sameAs\":[\"http:\\\/\\\/www.maurofelippe.com\"],\"url\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/author\\\/lc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Os Significados da P\u00e1scoa - Mauro Felippe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/","og_locale":"en_US","og_type":"article","og_title":"Os Significados da P\u00e1scoa - Mauro Felippe","og_description":"Desde crian\u00e7a (faz tempo), ou\u00e7o dizer: \u201cN\u00e3o se come carne na Sexta-Feira Santa porque \u00e9 Sexta-Feira Santa.\u201d \u00c9 uma das provas como a cultura, a tradi\u00e7\u00e3o, os dogmas, contagiam-nos a ponto de considerarmos, com efeito cogente, uma norma religiosa, psicologicamente imperdo\u00e1vel em caso de contrari\u00e1-la. &#8230; E o Z\u00e9 falou aos muitos amigos que o [&hellip;]","og_url":"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/","og_site_name":"Mauro Felippe","article_published_time":"2019-04-16T13:16:33+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Pa\u0301scoa-1024x1024.png","type":"image\/png"}],"author":"Mauro Felippe","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Mauro Felippe","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/#article","isPartOf":{"@id":"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/"},"author":{"name":"Mauro Felippe","@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"headline":"Os Significados da P\u00e1scoa","datePublished":"2019-04-16T13:16:33+00:00","mainEntityOfPage":{"@id":"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/"},"wordCount":850,"commentCount":0,"publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"image":{"@id":"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Pa\u0301scoa.png","keywords":["abril","b\u00edblia","Coelho","crist\u00e3","Igreja Cat\u00f3lica","Jesus Cristo","livro","Mauro Felippe","Ovos de P\u00e1scoa","P\u00e1scoa","poesia","ressurrei\u00e7\u00e3o","Sexta feira Santa"],"articleSection":["Artigos","Reflex\u00e3o e Cr\u00f4nicas"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/","url":"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/","name":"Os Significados da P\u00e1scoa - Mauro Felippe","isPartOf":{"@id":"http:\/\/maurofelippe.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/#primaryimage"},"image":{"@id":"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Pa\u0301scoa.png","datePublished":"2019-04-16T13:16:33+00:00","breadcrumb":{"@id":"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/#primaryimage","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Pa\u0301scoa.png","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Pa\u0301scoa.png","width":3333,"height":3333},{"@type":"BreadcrumbList","@id":"https:\/\/maurofelippe.com\/en\/os-significados-da-pascoa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maurofelippe.com\/"},{"@type":"ListItem","position":2,"name":"Os Significados da P\u00e1scoa"}]},{"@type":"WebSite","@id":"http:\/\/maurofelippe.com\/br\/#website","url":"http:\/\/maurofelippe.com\/br\/","name":"Mauro Felippe","description":"Author and Writer","publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/maurofelippe.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb","name":"Mauro Felippe","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","width":164,"height":86,"caption":"Mauro Felippe"},"logo":{"@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png"},"sameAs":["http:\/\/www.maurofelippe.com"],"url":"https:\/\/maurofelippe.com\/en\/author\/lc\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Pa\u0301scoa.png","jetpack_shortlink":"https:\/\/wp.me\/pavqH1-gN","jetpack-related-posts":[{"id":1065,"url":"https:\/\/maurofelippe.com\/en\/mauro-felippe-no-jornal-o-pioneiro\/","url_meta":{"origin":1041,"position":0},"title":"Mauro Felippe no Jornal O Pioneiro","author":"Mauro Felippe","date":"30\/04\/2019","format":false,"excerpt":"Confira o artigo do poeta e advogado Mauro Felippe publicado no jornal O Pioneiro, do Esp\u00edrito Santo.","rel":"","context":"In &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/en\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/15871788_1222787294436748_598680249592034171_n.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/15871788_1222787294436748_598680249592034171_n.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/15871788_1222787294436748_598680249592034171_n.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/15871788_1222787294436748_598680249592034171_n.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1062,"url":"https:\/\/maurofelippe.com\/en\/mauro-felippe-no-jornal-o-hoje\/","url_meta":{"origin":1041,"position":1},"title":"Mauro Felippe no Jornal O Hoje","author":"Mauro Felippe","date":"30\/04\/2019","format":false,"excerpt":"Confira o artigo do poeta e advogado Mauro Felippe publicado no jornal O Hoje, de Goi\u00e2nia.","rel":"","context":"In &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/en\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/fumo-espalhando-no-fundo-azul_23-2147785936.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/fumo-espalhando-no-fundo-azul_23-2147785936.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/fumo-espalhando-no-fundo-azul_23-2147785936.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1103,"url":"https:\/\/maurofelippe.com\/en\/dia-dos-namorados-nao-e-so-de-beijos-que-se-prova-o-amor\/","url_meta":{"origin":1041,"position":2},"title":"Dia dos namorados: &#8220;N\u00e3o \u00e9 s\u00f3 de beijos que se prova o amor&#8221;","author":"Mauro Felippe","date":"30\/05\/2019","format":false,"excerpt":"Uma data feita para celebrar a uni\u00e3o de casais apaixonados e intensificar o com\u00e9rcio. Entenda a origem dessa comemora\u00e7\u00e3o No Brasil, o\u00a0Dia dos Namorados\u00a0\u00e9 comemorado em 12 de Junho \u2013 com simbologia cat\u00f3lica, j\u00e1 que por sua vez, a data foi escolhida por ser v\u00e9spera do dia dedicado a\u00a0Santo Ant\u00f4nio.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/en\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/um-jovem-africano-propondo-a-namorada-dando-buque-de-flores-brancas_23-2148151780.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/um-jovem-africano-propondo-a-namorada-dando-buque-de-flores-brancas_23-2148151780.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/um-jovem-africano-propondo-a-namorada-dando-buque-de-flores-brancas_23-2148151780.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":2027,"url":"https:\/\/maurofelippe.com\/en\/mauro-felippe-no-espirito-santo-noticias\/","url_meta":{"origin":1041,"position":3},"title":"MAURO FELIPPE NO Esp\u00edrito Santo Not\u00edcias&#8217;","author":"Mauro Felippe","date":"09\/09\/2023","format":false,"excerpt":"Nova mat\u00e9ria sobre o meu novo livro CATARSE, pela Lura Editorial. Obrigado, 'Esp\u00edrito Santo Not\u00edcias', pelo release no Portal\/Jornal, via Sudeste do Pa\u00eds. Mat\u00e9ria completa clica aqui: https:\/\/www.espiritosantonoticias.com.br\/o-caos-da...\/... Obrigado! \u00a0Livros e livrarias aqui:\u00a0http:\/\/linktr.ee\/maurofelippe Contato com o autor e redes sociais: Facebook:\u00a0https:\/\/www.facebook.com\/MauroFelippeAutor Instagram:\u00a0www.Instagram.com\/maurofelippe Youtube:\u00a0www.Youtube.com\/maurofelippe Linktree:\u00a0https:\/\/linktr.ee\/maurofelippe . #maurofelippe#luraeditorial#espiritosanto#espiritosantonoticias#literatura#instalivros#bienaldolivro#poesia#poes\u00eda#catarse#livros#lan\u00e7amento","rel":"","context":"In &quot;Mat\u00e9rias publicadas&quot;","block_context":{"text":"Mat\u00e9rias publicadas","link":"https:\/\/maurofelippe.com\/en\/category\/materias-publicadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/image-8.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/image-8.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/image-8.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1088,"url":"https:\/\/maurofelippe.com\/en\/mauro-felippe-no-jornal-o-atlantico\/","url_meta":{"origin":1041,"position":4},"title":"Mauro Felippe no jornal O Atl\u00e2ntico","author":"Mauro Felippe","date":"13\/05\/2019","format":false,"excerpt":"Confira o artigo sobre o \u201cDia da L\u00edngua Portuguesa\u201d, do poeta e advogado Mauro Felippe publicado no jornal impresso O Atl\u00e2ntico de Santa Catarina. \u00a0","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/en\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/fumo-espalhando-no-fundo-azul_23-2147785936.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/fumo-espalhando-no-fundo-azul_23-2147785936.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/fumo-espalhando-no-fundo-azul_23-2147785936.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1607,"url":"https:\/\/maurofelippe.com\/en\/everaldo-luiz-thomaz\/","url_meta":{"origin":1041,"position":5},"title":"EVERALDO LUIZ THOMAZ","author":"Mauro Felippe","date":"07\/07\/2023","format":false,"excerpt":"06.07.2023. Um dia triste, ao saber da passagem de EVERALDO LUIZ THOMAZ, amigo e artista que fez em PURO GRAFITE a imagem de CRISTO (foto abaixo), especialmente a pedido para a ilustra\u00e7\u00e3o de um dos meus textos. Artista de sensibilidade impressionante. Esta postagem em meu Facebook (Clique aqui) fiz em\u2026","rel":"","context":"In &quot;Reflex\u00e3o e Cr\u00f4nicas&quot;","block_context":{"text":"Reflex\u00e3o e Cr\u00f4nicas","link":"https:\/\/maurofelippe.com\/en\/category\/reflexao-e-cronicas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/07\/THOMAZ-ART.gif?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/07\/THOMAZ-ART.gif?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/07\/THOMAZ-ART.gif?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/07\/THOMAZ-ART.gif?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/posts\/1041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/comments?post=1041"}],"version-history":[{"count":4,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/posts\/1041\/revisions"}],"predecessor-version":[{"id":1046,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/posts\/1041\/revisions\/1046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/media\/1042"}],"wp:attachment":[{"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/media?parent=1041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/categories?post=1041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/tags?post=1041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}