{"id":1080,"date":"2019-05-03T15:00:39","date_gmt":"2019-05-03T18:00:39","guid":{"rendered":"https:\/\/maurofelippe.com\/?p=1080"},"modified":"2019-05-03T15:00:39","modified_gmt":"2019-05-03T18:00:39","slug":"portugues-nossa-lingua-materna","status":"publish","type":"post","link":"https:\/\/maurofelippe.com\/en\/portugues-nossa-lingua-materna\/","title":{"rendered":"Portugu\u00eas, nossa l\u00edngua materna"},"content":{"rendered":"<p><span style=\"color: #000000;\">Anualmente, no dia 5 de Maio, comemora-se <strong>o Dia da L\u00edngua Portuguesa. <\/strong>Essa data \u00e9 celebrada apenas entre os pa\u00edses lus\u00f3fonos \u2013 aqueles que t\u00eam como sua l\u00edngua materna o portugu\u00eas.<\/span><\/p>\n<p><span style=\"color: #000000;\">Curiosamente, o portugu\u00eas surgiu da mesma l\u00edngua que originou a maioria dos idiomas europeus e asi\u00e1ticos. Com as in\u00fameras migra\u00e7\u00f5es entre os Continentes, a l\u00edngua inicial existente acabou subdividida em cinco ramos: o hel\u00eanico, de onde veio o idioma grego; o rom\u00e2nico, que originou o portugu\u00eas, o italiano, o franc\u00eas e uma s\u00e9rie de outras l\u00ednguas denominadas latinas; o germ\u00e2nico, de onde surgiram o ingl\u00eas e o alem\u00e3o; e finalmente o c\u00e9ltico, que deu origem aos idiomas irland\u00eas e ga\u00e9lico.<\/span><\/p>\n<p><span style=\"color: #000000;\">O nosso idioma, foi originado no <strong>Galego-Portugu\u00eas<\/strong>, l\u00edngua falada no Reino da Galiza e no norte de Portugal. Os portugueses foram os primeiros europeus a lan\u00e7ar-se ao mar no per\u00edodo das Grandes Navega\u00e7\u00f5es, assim disseminando sua fala para outros povos em diferentes sociedades.<\/span><\/p>\n<p><span style=\"color: #000000;\">Com a motiva\u00e7\u00e3o comercial \u00a0deu-se a difus\u00e3o de l\u00ednguas nas terras conquistadas, dentre elas o Brasil, cuja l\u00edngua prim\u00e1ria, sem contar as linguagens ind\u00edgenas, \u00e9 o portugu\u00eas. A influ\u00eancia da cultura portuguesa por aqui foi tamanha que acabou definindo o idioma oficial da terra rec\u00e9m-conquistada. O mesmo aconteceu em outras partes do mundo, principalmente na \u00c1frica, onde pa\u00edses como Mo\u00e7ambique, Angola, Cabo Verde, Guin\u00e9 Equatorial, Guin\u00e9-Bissau, S\u00e3o Tom\u00e9 e Timor-Leste.<\/span><\/p>\n<p><span style=\"color: #000000;\">O portugu\u00eas, assim como v\u00e1rios outros idiomas, sofreu uma evolu\u00e7\u00e3o hist\u00f3rica, fato que comprova a organicidade de nossa l\u00edngua, que em muitos aspectos \u00e9 diferente do portugu\u00eas falado e escrito de Portugal, tendo diverg\u00eancia de significados de palavras e pronuncias.<\/span><\/p>\n<p><span style=\"color: #000000;\">Tais diferen\u00e7as deram origem a dois padr\u00f5es de linguagem diversos, o que n\u00e3o significa que um seja mais correto do que o outro. Nossa l\u00edngua \u00e9 rica em variedades, sobretudo regionais, como as diferen\u00e7as lingu\u00edsticas encontradas em nosso pr\u00f3prio territ\u00f3rio por conta da cria\u00e7\u00e3o de neologismo, ou seja, elaborar uma palavra ou express\u00f5es novas, adquirindo assim, um linguajar pr\u00f3prio em meio ao nosso idioma. Entretanto, n\u00e3o inviabilizam a compreens\u00e3o, ainda que dificuldades pontuais possam aparecer.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Anualmente, no dia 5 de Maio, comemora-se o Dia da L\u00edngua Portuguesa. Essa data \u00e9 celebrada apenas entre os pa\u00edses lus\u00f3fonos \u2013 aqueles que t\u00eam como sua l\u00edngua materna o portugu\u00eas. Curiosamente, o portugu\u00eas surgiu da mesma l\u00edngua que originou a maioria dos idiomas europeus e asi\u00e1ticos. Com as in\u00fameras migra\u00e7\u00f5es entre os Continentes, a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1081,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,31],"tags":[144,237,335,340,336,338,33,337,339],"class_list":["post-1080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-reflexao-e-cronicas","tag-artigo","tag-brasil","tag-dia-internacional-da-lingua-portuguesa","tag-lingua-materna","tag-lingua-portuguesa","tag-lusofonos","tag-mauro-felippe","tag-paises","tag-portugues"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portugu\u00eas, nossa l\u00edngua materna - Mauro Felippe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/maurofelippe.com\/en\/portugues-nossa-lingua-materna\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portugu\u00eas, nossa l\u00edngua materna - Mauro Felippe\" \/>\n<meta property=\"og:description\" content=\"Anualmente, no dia 5 de Maio, comemora-se o Dia da L\u00edngua Portuguesa. Essa data \u00e9 celebrada apenas entre os pa\u00edses lus\u00f3fonos \u2013 aqueles que t\u00eam como sua l\u00edngua materna o portugu\u00eas. Curiosamente, o portugu\u00eas surgiu da mesma l\u00edngua que originou a maioria dos idiomas europeus e asi\u00e1ticos. Com as in\u00fameras migra\u00e7\u00f5es entre os Continentes, a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/maurofelippe.com\/en\/portugues-nossa-lingua-materna\/\" \/>\n<meta property=\"og:site_name\" content=\"Mauro Felippe\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-03T18:00:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/pot.png\" \/>\n\t<meta property=\"og:image:width\" content=\"345\" \/>\n\t<meta property=\"og:image:height\" content=\"249\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mauro Felippe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mauro Felippe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/portugues-nossa-lingua-materna\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/portugues-nossa-lingua-materna\\\/\"},\"author\":{\"name\":\"Mauro Felippe\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"headline\":\"Portugu\u00eas, nossa l\u00edngua materna\",\"datePublished\":\"2019-05-03T18:00:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/portugues-nossa-lingua-materna\\\/\"},\"wordCount\":401,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"image\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/portugues-nossa-lingua-materna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/pot.png\",\"keywords\":[\"artigo\",\"brasil\",\"Dia internacional da L\u00edngua Portuguesa\",\"L\u00edngua Materna\",\"L\u00edngua Portuguesa\",\"lus\u00f3fonos\",\"Mauro Felippe\",\"Pa\u00edses\",\"Portugu\u00eas\"],\"articleSection\":[\"Artigos\",\"Reflex\u00e3o e Cr\u00f4nicas\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/maurofelippe.com\\\/br\\\/portugues-nossa-lingua-materna\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/portugues-nossa-lingua-materna\\\/\",\"url\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/portugues-nossa-lingua-materna\\\/\",\"name\":\"Portugu\u00eas, nossa l\u00edngua materna - Mauro Felippe\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/portugues-nossa-lingua-materna\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/portugues-nossa-lingua-materna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/pot.png\",\"datePublished\":\"2019-05-03T18:00:39+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/portugues-nossa-lingua-materna\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/maurofelippe.com\\\/br\\\/portugues-nossa-lingua-materna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/portugues-nossa-lingua-materna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/pot.png\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/pot.png\",\"width\":345,\"height\":249},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/portugues-nossa-lingua-materna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maurofelippe.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portugu\u00eas, nossa l\u00edngua materna\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\",\"url\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/\",\"name\":\"Mauro Felippe\",\"description\":\"Autor e Escritor\",\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\",\"name\":\"Mauro Felippe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"width\":164,\"height\":86,\"caption\":\"Mauro Felippe\"},\"logo\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\"},\"sameAs\":[\"http:\\\/\\\/www.maurofelippe.com\"],\"url\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/author\\\/lc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portugu\u00eas, nossa l\u00edngua materna - Mauro Felippe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/maurofelippe.com\/en\/portugues-nossa-lingua-materna\/","og_locale":"en_US","og_type":"article","og_title":"Portugu\u00eas, nossa l\u00edngua materna - Mauro Felippe","og_description":"Anualmente, no dia 5 de Maio, comemora-se o Dia da L\u00edngua Portuguesa. Essa data \u00e9 celebrada apenas entre os pa\u00edses lus\u00f3fonos \u2013 aqueles que t\u00eam como sua l\u00edngua materna o portugu\u00eas. Curiosamente, o portugu\u00eas surgiu da mesma l\u00edngua que originou a maioria dos idiomas europeus e asi\u00e1ticos. Com as in\u00fameras migra\u00e7\u00f5es entre os Continentes, a [&hellip;]","og_url":"http:\/\/maurofelippe.com\/en\/portugues-nossa-lingua-materna\/","og_site_name":"Mauro Felippe","article_published_time":"2019-05-03T18:00:39+00:00","og_image":[{"width":345,"height":249,"url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/pot.png","type":"image\/png"}],"author":"Mauro Felippe","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Mauro Felippe","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/maurofelippe.com\/br\/portugues-nossa-lingua-materna\/#article","isPartOf":{"@id":"http:\/\/maurofelippe.com\/br\/portugues-nossa-lingua-materna\/"},"author":{"name":"Mauro Felippe","@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"headline":"Portugu\u00eas, nossa l\u00edngua materna","datePublished":"2019-05-03T18:00:39+00:00","mainEntityOfPage":{"@id":"http:\/\/maurofelippe.com\/br\/portugues-nossa-lingua-materna\/"},"wordCount":401,"commentCount":0,"publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"image":{"@id":"http:\/\/maurofelippe.com\/br\/portugues-nossa-lingua-materna\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/pot.png","keywords":["artigo","brasil","Dia internacional da L\u00edngua Portuguesa","L\u00edngua Materna","L\u00edngua Portuguesa","lus\u00f3fonos","Mauro Felippe","Pa\u00edses","Portugu\u00eas"],"articleSection":["Artigos","Reflex\u00e3o e Cr\u00f4nicas"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/maurofelippe.com\/br\/portugues-nossa-lingua-materna\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/maurofelippe.com\/br\/portugues-nossa-lingua-materna\/","url":"http:\/\/maurofelippe.com\/br\/portugues-nossa-lingua-materna\/","name":"Portugu\u00eas, nossa l\u00edngua materna - Mauro Felippe","isPartOf":{"@id":"http:\/\/maurofelippe.com\/br\/#website"},"primaryImageOfPage":{"@id":"http:\/\/maurofelippe.com\/br\/portugues-nossa-lingua-materna\/#primaryimage"},"image":{"@id":"http:\/\/maurofelippe.com\/br\/portugues-nossa-lingua-materna\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/pot.png","datePublished":"2019-05-03T18:00:39+00:00","breadcrumb":{"@id":"http:\/\/maurofelippe.com\/br\/portugues-nossa-lingua-materna\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/maurofelippe.com\/br\/portugues-nossa-lingua-materna\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/maurofelippe.com\/br\/portugues-nossa-lingua-materna\/#primaryimage","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/pot.png","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/pot.png","width":345,"height":249},{"@type":"BreadcrumbList","@id":"http:\/\/maurofelippe.com\/br\/portugues-nossa-lingua-materna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maurofelippe.com\/"},{"@type":"ListItem","position":2,"name":"Portugu\u00eas, nossa l\u00edngua materna"}]},{"@type":"WebSite","@id":"http:\/\/maurofelippe.com\/br\/#website","url":"http:\/\/maurofelippe.com\/br\/","name":"Mauro Felippe","description":"Author and Writer","publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/maurofelippe.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb","name":"Mauro Felippe","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","width":164,"height":86,"caption":"Mauro Felippe"},"logo":{"@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png"},"sameAs":["http:\/\/www.maurofelippe.com"],"url":"https:\/\/maurofelippe.com\/en\/author\/lc\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/pot.png","jetpack_shortlink":"https:\/\/wp.me\/pavqH1-hq","jetpack-related-posts":[{"id":1092,"url":"https:\/\/maurofelippe.com\/en\/mauro-felippe-no-jornal-tribuna-do-planalto\/","url_meta":{"origin":1080,"position":0},"title":"Mauro Felippe no jornal Tribuna do Planalto","author":"Mauro Felippe","date":"13\/05\/2019","format":false,"excerpt":"Confira o artigo sobre o \u201cDia da L\u00edngua Portuguesa\u201d, do poeta e advogado Mauro Felippe publicado na coluna do jornal impresso Tribuna do Planalto . \u00a0","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/en\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1088,"url":"https:\/\/maurofelippe.com\/en\/mauro-felippe-no-jornal-o-atlantico\/","url_meta":{"origin":1080,"position":1},"title":"Mauro Felippe no jornal O Atl\u00e2ntico","author":"Mauro Felippe","date":"13\/05\/2019","format":false,"excerpt":"Confira o artigo sobre o \u201cDia da L\u00edngua Portuguesa\u201d, do poeta e advogado Mauro Felippe publicado no jornal impresso O Atl\u00e2ntico de Santa Catarina. \u00a0","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/en\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/fumo-espalhando-no-fundo-azul_23-2147785936.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/fumo-espalhando-no-fundo-azul_23-2147785936.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/05\/fumo-espalhando-no-fundo-azul_23-2147785936.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1037,"url":"https:\/\/maurofelippe.com\/en\/dia-do-indio-uma-heranca-cultural-e-etnica\/","url_meta":{"origin":1080,"position":2},"title":"Dia do \u00edndio: Uma heran\u00e7a cultural e \u00e9tnica","author":"Mauro Felippe","date":"11\/04\/2019","format":false,"excerpt":"Uma data especial para relembrar a import\u00e2ncia cultural e hist\u00f3rica dos \u00edndios, o dia 19 de Abril foi escolhido gra\u00e7as ao 1\u00b0 Congresso Indigenista Interamericano, que ocorreu em 1940 \u201cOs por eles chamados Amer\u00edndios daqui Falavam como \u00edndios Depois como os portugueses Americanos, ingleses Os Amer\u00edndios... [...] Tantas l\u00ednguas goela\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/en\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_do_I%CC%81ndio.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_do_I%CC%81ndio.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_do_I%CC%81ndio.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_do_I%CC%81ndio.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_do_I%CC%81ndio.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/Dia_do_I%CC%81ndio.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":989,"url":"https:\/\/maurofelippe.com\/en\/poesia-a-alma-dos-poetas\/","url_meta":{"origin":1080,"position":3},"title":"Poesia: a alma dos poetas","author":"Mauro Felippe","date":"11\/03\/2019","format":false,"excerpt":"A poesia \u00e9 uma das sete artes tradicionais pela qual a linguagem humana \u00e9 utilizada com fins est\u00e9ticos ou cr\u00edticos. \u00c9 um texto onde o autor expressa diretamente sentimentos e vis\u00f5es pessoais e do mundo. A voz que se manifesta na poesia, ou seja, o sujeito po\u00e9tico e fict\u00edcio, criado\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/en\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/livro-imagem-generalista_0.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/livro-imagem-generalista_0.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/livro-imagem-generalista_0.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/livro-imagem-generalista_0.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/livro-imagem-generalista_0.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/03\/livro-imagem-generalista_0.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":1054,"url":"https:\/\/maurofelippe.com\/en\/dia-da-literatura-brasileira-a-arte-da-palavra\/","url_meta":{"origin":1080,"position":4},"title":"Dia da Literatura Brasileira: a arte da palavra","author":"Mauro Felippe","date":"29\/04\/2019","format":false,"excerpt":"\u00a0[...] As palavras t\u00eam vidas Umas fazem-nos saltitar E, quando menos tranquilas Mais atraentes ficam Fazem os olhos brilhar. Livros s\u00e3o fontes que transbordam Nenhum animal descreve o passado Nem o que ocorre no presente Nem desenha o futuro O homem, ao menos, desabafa escrevendo. As tipografias s\u00e3o capazes disto\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/en\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/c1d48818-c3b4-45e4-b52c-fe2cd221511d.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/c1d48818-c3b4-45e4-b52c-fe2cd221511d.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/c1d48818-c3b4-45e4-b52c-fe2cd221511d.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/c1d48818-c3b4-45e4-b52c-fe2cd221511d.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2019\/04\/c1d48818-c3b4-45e4-b52c-fe2cd221511d.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":1518,"url":"https:\/\/maurofelippe.com\/en\/feliz-dia-nacional-do-livro\/","url_meta":{"origin":1080,"position":5},"title":"Feliz Dia Nacional do Livro","author":"Mauro Felippe","date":"29\/10\/2021","format":false,"excerpt":"Celebrado anualmente em 29\/10, o Dia Nacional do Livro surgiu em homenagem \u00e0 funda\u00e7\u00e3o da Biblioteca Nacional do Livro, do Rio de Janeiro-RJ, em 29\/10\/1810, pela Coroa Portuguesa. Na \u00e9poca, D. Jo\u00e3o VI trouxe para o Brasil milhares de pe\u00e7as da Real Biblioteca Portuguesa. Hoje, possui mais de 9 milh\u00f5es\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/maurofelippe.com\/en\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2021\/10\/maurofelippe-249829458_578183456739438_8450357111724729358_n.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2021\/10\/maurofelippe-249829458_578183456739438_8450357111724729358_n.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2021\/10\/maurofelippe-249829458_578183456739438_8450357111724729358_n.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2021\/10\/maurofelippe-249829458_578183456739438_8450357111724729358_n.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/posts\/1080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/comments?post=1080"}],"version-history":[{"count":2,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/posts\/1080\/revisions"}],"predecessor-version":[{"id":1083,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/posts\/1080\/revisions\/1083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/media\/1081"}],"wp:attachment":[{"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/media?parent=1080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/categories?post=1080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/tags?post=1080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}