{"id":2041,"date":"2023-09-10T18:00:00","date_gmt":"2023-09-10T21:00:00","guid":{"rendered":"https:\/\/maurofelippe.com\/?p=2041"},"modified":"2023-09-09T11:13:22","modified_gmt":"2023-09-09T14:13:22","slug":"catarse-no-site-do-imirante-com","status":"publish","type":"post","link":"https:\/\/maurofelippe.com\/en\/catarse-no-site-do-imirante-com\/","title":{"rendered":"CATARSE, no Site do Imirante.com"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"526\" height=\"526\" src=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-3.png\" alt=\"\" class=\"wp-image-2042\" srcset=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-3.png 526w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-3-300x300.png 300w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-3-150x150.png 150w, https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-3-12x12.png 12w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/><\/figure>\n\n\n\n<p>CATARSE, no Site do <a href=\"https:\/\/www.facebook.com\/portalimirante?__cft__[0]=AZWJVLen104c_-rEDXLAEw9PlPdvFOnH6K55VKQzD04CSc4WjaNJf6RBk3YJ6K6WF6GbrmvHOYCwPEzmtsvt1r8rLTKf2O0gu1Vy5hz2j1i3tOaRUvP5TIzCjRq2hP412Nxy0whqOM7OzVunXy72JjtM_si35A68PObQWbzmiKjk3gKBC0AOajMp7hmbm9A1f9c&amp;__tn__=-]K-R\">Imirante.com<\/a>, do Grupo Mirante, o maior de comunica\u00e7\u00f5es do Maranh\u00e3o.<\/p>\n\n\n\n<p>Mat\u00e9ria completa j\u00e1 postada no meu Site e demais redes, e no pr\u00f3prio Imirante, que desde j\u00e1 o agrade\u00e7o! Acesse-a completa clicando diretamente aqui: <a href=\"https:\/\/imirante.com\/namira\/sao-luis\/2023\/08\/23\/autor-propoe-volta-ds-literatura-reflexiva-em-nova-obra?fbclid=IwAR2yOkieSdefynTwFi0UC69_9i88jBcURFDItmrCFOD85EPWUEYGXfIl6lo\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/imirante.com\/&#8230;\/autor-propoe-volta-ds-literatura&#8230;<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><img decoding=\"async\" height=\"16\" width=\"16\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/taa\/1\/16\/1f310.png\" alt=\"?\">&nbsp;Livros e livrarias aqui:<a href=\"http:\/\/linktr.ee\/maurofelippe?fbclid=IwAR22vlmRT1hyJK6T2EGjGstrkx81GpSKjPOyxubatJPcy6599esAsjm1NYI\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;<\/a><a href=\"http:\/\/linktr.ee\/maurofelippe\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/linktr.ee\/maurofelipp<strong>e<\/strong><\/a><\/p>\n\n\n\n<p>Contato com o autor e redes sociais:<\/p>\n\n\n\n<p>Facebook:<strong>&nbsp;<a href=\"https:\/\/www.facebook.com\/MauroFelippeAutor\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/MauroFelippeAutor<\/a><\/strong><\/p>\n\n\n\n<p>Instagram:&nbsp;<a href=\"http:\/\/www.instagram.com\/maurofelippe\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>www.Instagram.com\/maurofelippe<\/strong><\/a><\/p>\n\n\n\n<p>Youtube:&nbsp;<a href=\"https:\/\/www.youtube.com\/channel\/UC7WCtqQrUUWkiTer1n_kUTQ\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>www.Youtube.com\/maurofelippe<\/strong><\/a><\/p>\n\n\n\n<p>Linktree:&nbsp;<a href=\"https:\/\/linktr.ee\/maurofelippe\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>https:\/\/linktr.ee\/maurofelippe<\/strong><\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATARSE, no Site do Imirante.com, do Grupo Mirante, o maior de comunica\u00e7\u00f5es do Maranh\u00e3o. Mat\u00e9ria completa j\u00e1 postada no meu Site e demais redes, e no pr\u00f3prio Imirante, que desde j\u00e1 o agrade\u00e7o! Acesse-a completa clicando diretamente aqui: https:\/\/imirante.com\/&#8230;\/autor-propoe-volta-ds-literatura&#8230; &nbsp;Livros e livrarias aqui:&nbsp;http:\/\/linktr.ee\/maurofelippe Contato com o autor e redes sociais: Facebook:&nbsp;https:\/\/www.facebook.com\/MauroFelippeAutor Instagram:&nbsp;www.Instagram.com\/maurofelippe Youtube:&nbsp;www.Youtube.com\/maurofelippe Linktree:&nbsp;https:\/\/linktr.ee\/maurofelippe<\/p>","protected":false},"author":2,"featured_media":2043,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,176],"tags":[431,620,532,624,38,78,623,33,41,37,80],"class_list":["post-2041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-imprensa","category-materias-publicadas","tag-bienal","tag-bienaldolivrorio2023","tag-catarse","tag-imirante","tag-literatura","tag-livro","tag-lura","tag-mauro-felippe","tag-obras","tag-poesia","tag-poeta"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CATARSE, no Site do Imirante.com - Mauro Felippe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maurofelippe.com\/en\/catarse-no-site-do-imirante-com\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CATARSE, no Site do Imirante.com - Mauro Felippe\" \/>\n<meta property=\"og:description\" content=\"CATARSE, no Site do Imirante.com, do Grupo Mirante, o maior de comunica\u00e7\u00f5es do Maranh\u00e3o. Mat\u00e9ria completa j\u00e1 postada no meu Site e demais redes, e no pr\u00f3prio Imirante, que desde j\u00e1 o agrade\u00e7o! Acesse-a completa clicando diretamente aqui: https:\/\/imirante.com\/&#8230;\/autor-propoe-volta-ds-literatura&#8230; &nbsp;Livros e livrarias aqui:&nbsp;http:\/\/linktr.ee\/maurofelippe Contato com o autor e redes sociais: Facebook:&nbsp;https:\/\/www.facebook.com\/MauroFelippeAutor Instagram:&nbsp;www.Instagram.com\/maurofelippe Youtube:&nbsp;www.Youtube.com\/maurofelippe Linktree:&nbsp;https:\/\/linktr.ee\/maurofelippe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maurofelippe.com\/en\/catarse-no-site-do-imirante-com\/\" \/>\n<meta property=\"og:site_name\" content=\"Mauro Felippe\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-10T21:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mauro Felippe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mauro Felippe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-no-site-do-imirante-com\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-no-site-do-imirante-com\\\/\"},\"author\":{\"name\":\"Mauro Felippe\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"headline\":\"CATARSE, no Site do Imirante.com\",\"datePublished\":\"2023-09-10T21:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-no-site-do-imirante-com\\\/\"},\"wordCount\":96,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"image\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-no-site-do-imirante-com\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/image-4.png\",\"keywords\":[\"bienal\",\"bienaldolivrorio2023\",\"Catarse\",\"Imirante\",\"literatura\",\"livro\",\"Lura\",\"Mauro Felippe\",\"obras\",\"poesia\",\"poeta\"],\"articleSection\":[\"Imprensa\",\"Mat\u00e9rias publicadas\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maurofelippe.com\\\/catarse-no-site-do-imirante-com\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-no-site-do-imirante-com\\\/\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-no-site-do-imirante-com\\\/\",\"name\":\"CATARSE, no Site do Imirante.com - Mauro Felippe\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-no-site-do-imirante-com\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-no-site-do-imirante-com\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/image-4.png\",\"datePublished\":\"2023-09-10T21:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-no-site-do-imirante-com\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maurofelippe.com\\\/catarse-no-site-do-imirante-com\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-no-site-do-imirante-com\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/image-4.png\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/image-4.png\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/catarse-no-site-do-imirante-com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maurofelippe.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CATARSE, no Site do Imirante.com\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#website\",\"url\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/\",\"name\":\"Mauro Felippe\",\"description\":\"Autor e Escritor\",\"publisher\":{\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/maurofelippe.com\\\/br\\\/#\\\/schema\\\/person\\\/b6fb66bfeb28cbb8e687e43244e365cb\",\"name\":\"Mauro Felippe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"url\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"contentUrl\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\",\"width\":164,\"height\":86,\"caption\":\"Mauro Felippe\"},\"logo\":{\"@id\":\"https:\\\/\\\/maurofelippe.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/logo-Mauro-Felippe.png\"},\"sameAs\":[\"http:\\\/\\\/www.maurofelippe.com\"],\"url\":\"https:\\\/\\\/maurofelippe.com\\\/en\\\/author\\\/lc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CATARSE, no Site do Imirante.com - Mauro Felippe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maurofelippe.com\/en\/catarse-no-site-do-imirante-com\/","og_locale":"en_US","og_type":"article","og_title":"CATARSE, no Site do Imirante.com - Mauro Felippe","og_description":"CATARSE, no Site do Imirante.com, do Grupo Mirante, o maior de comunica\u00e7\u00f5es do Maranh\u00e3o. Mat\u00e9ria completa j\u00e1 postada no meu Site e demais redes, e no pr\u00f3prio Imirante, que desde j\u00e1 o agrade\u00e7o! Acesse-a completa clicando diretamente aqui: https:\/\/imirante.com\/&#8230;\/autor-propoe-volta-ds-literatura&#8230; &nbsp;Livros e livrarias aqui:&nbsp;http:\/\/linktr.ee\/maurofelippe Contato com o autor e redes sociais: Facebook:&nbsp;https:\/\/www.facebook.com\/MauroFelippeAutor Instagram:&nbsp;www.Instagram.com\/maurofelippe Youtube:&nbsp;www.Youtube.com\/maurofelippe Linktree:&nbsp;https:\/\/linktr.ee\/maurofelippe","og_url":"https:\/\/maurofelippe.com\/en\/catarse-no-site-do-imirante-com\/","og_site_name":"Mauro Felippe","article_published_time":"2023-09-10T21:00:00+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-4.png","type":"image\/png"}],"author":"Mauro Felippe","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Mauro Felippe","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maurofelippe.com\/catarse-no-site-do-imirante-com\/#article","isPartOf":{"@id":"https:\/\/maurofelippe.com\/catarse-no-site-do-imirante-com\/"},"author":{"name":"Mauro Felippe","@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"headline":"CATARSE, no Site do Imirante.com","datePublished":"2023-09-10T21:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/maurofelippe.com\/catarse-no-site-do-imirante-com\/"},"wordCount":96,"commentCount":0,"publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"image":{"@id":"https:\/\/maurofelippe.com\/catarse-no-site-do-imirante-com\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-4.png","keywords":["bienal","bienaldolivrorio2023","Catarse","Imirante","literatura","livro","Lura","Mauro Felippe","obras","poesia","poeta"],"articleSection":["Imprensa","Mat\u00e9rias publicadas"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maurofelippe.com\/catarse-no-site-do-imirante-com\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maurofelippe.com\/catarse-no-site-do-imirante-com\/","url":"https:\/\/maurofelippe.com\/catarse-no-site-do-imirante-com\/","name":"CATARSE, no Site do Imirante.com - Mauro Felippe","isPartOf":{"@id":"http:\/\/maurofelippe.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maurofelippe.com\/catarse-no-site-do-imirante-com\/#primaryimage"},"image":{"@id":"https:\/\/maurofelippe.com\/catarse-no-site-do-imirante-com\/#primaryimage"},"thumbnailUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-4.png","datePublished":"2023-09-10T21:00:00+00:00","breadcrumb":{"@id":"https:\/\/maurofelippe.com\/catarse-no-site-do-imirante-com\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maurofelippe.com\/catarse-no-site-do-imirante-com\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maurofelippe.com\/catarse-no-site-do-imirante-com\/#primaryimage","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-4.png","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-4.png","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/maurofelippe.com\/catarse-no-site-do-imirante-com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maurofelippe.com\/"},{"@type":"ListItem","position":2,"name":"CATARSE, no Site do Imirante.com"}]},{"@type":"WebSite","@id":"http:\/\/maurofelippe.com\/br\/#website","url":"http:\/\/maurofelippe.com\/br\/","name":"Mauro Felippe","description":"Author and Writer","publisher":{"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/maurofelippe.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"http:\/\/maurofelippe.com\/br\/#\/schema\/person\/b6fb66bfeb28cbb8e687e43244e365cb","name":"Mauro Felippe","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","contentUrl":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png","width":164,"height":86,"caption":"Mauro Felippe"},"logo":{"@id":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2019\/01\/logo-Mauro-Felippe.png"},"sameAs":["http:\/\/www.maurofelippe.com"],"url":"https:\/\/maurofelippe.com\/en\/author\/lc\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-4.png","jetpack_shortlink":"https:\/\/wp.me\/pavqH1-wV","jetpack-related-posts":[{"id":2037,"url":"https:\/\/maurofelippe.com\/en\/catarse-no-jornal-correio-popular\/","url_meta":{"origin":2041,"position":0},"title":"CATARSE, no Jornal Correio Popular","author":"Mauro Felippe","date":"10\/09\/2023","format":false,"excerpt":"CATARSE, no Jornal Correio Popular, de Campinas-SP, na Coluna 'Societ\u00e1', do Jornalista Almir Reis (cr\u00e9ditos de Amor Reis). #saopaulo#campinas#campinassp Mat\u00e9ria completa j\u00e1 postada no meu Site e demais redes, e no pr\u00f3prio Jornal, que desde j\u00e1 o agrade\u00e7o! \u00a0Livros e livrarias aqui:\u00a0http:\/\/linktr.ee\/maurofelippe Contato com o autor e redes sociais: Facebook:\u00a0https:\/\/www.facebook.com\/MauroFelippeAutor\u2026","rel":"","context":"In &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/en\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-2.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2050,"url":"https:\/\/maurofelippe.com\/en\/2050-2\/","url_meta":{"origin":2041,"position":1},"title":"CATARSE, no Blog &#8216;Acontece&#8217;","author":"Mauro Felippe","date":"12\/09\/2023","format":false,"excerpt":"CATARSE, no Blog 'Acontece', do Esp\u00edrito Santo - ES. Entrevista completa j\u00e1 postada no meu Site, demais redes, e no pr\u00f3prio Blog, que desde j\u00e1 o agrade\u00e7o! Acesse a entrevista completa clicando diretamente aqui: http:\/\/acontecesantyago.blogspot.com\/...\/o-caos-da... Obrigado! \u00a0Livros e livrarias aqui:\u00a0http:\/\/linktr.ee\/maurofelippe Contato com o autor e redes sociais: Facebook:\u00a0https:\/\/www.facebook.com\/MauroFelippeAutor Instagram:\u00a0www.Instagram.com\/maurofelippe Youtube:\u00a0www.Youtube.com\/maurofelippe\u2026","rel":"","context":"In &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/en\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-8.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-8.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-8.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":2046,"url":"https:\/\/maurofelippe.com\/en\/catarse-no-portal-meia-92\/","url_meta":{"origin":2041,"position":2},"title":"CATARSE, no Portal Meia 92","author":"Mauro Felippe","date":"11\/09\/2023","format":false,"excerpt":"CATARSE, no @portalmeia92, de S\u00e3o Paulo-SP. Belo portal de entretenimento. Entrevista completa no pr\u00f3prio Portal, que desde j\u00e1 o agrade\u00e7o! Acesse a entrevista completa clicando diretamente aqui: https:\/\/meia92.com.br\/...\/em-entrevista-escritor-mauro...\/ Obrigado! \u00a0Livros e livrarias aqui:\u00a0http:\/\/linktr.ee\/maurofelippe Contato com o autor e redes sociais: Facebook:\u00a0https:\/\/www.facebook.com\/MauroFelippeAutor Instagram:\u00a0www.Instagram.com\/maurofelippe Youtube:\u00a0www.Youtube.com\/maurofelippe Linktree:\u00a0https:\/\/linktr.ee\/maurofelippe","rel":"","context":"In &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/en\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/09\/image-6.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1995,"url":"https:\/\/maurofelippe.com\/en\/mauro-felippe-no-mi-mood\/","url_meta":{"origin":2041,"position":3},"title":"Mauro Felippe no Mi Mood","author":"Mauro Felippe","date":"26\/08\/2023","format":false,"excerpt":"Nova mat\u00e9ria sobre o novo livro de Mauro Felippe CATARSE, pela Lura Editorial. Obrigado, Mimood, pelo release no Blog, via Sudeste do Pa\u00eds. Mat\u00e9ria completa clique aqui: https:\/\/mimood.com.br\/...\/catarse-poesia-que-transcende...\/ Obrigado! Contato com o autor e redes sociais: Facebook:\u00a0https:\/\/www.facebook.com\/MauroFelippeAutor Instagram:\u00a0www.Instagram.com\/maurofelippe Youtube:\u00a0www.Youtube.com\/maurofelippe Linktree:\u00a0https:\/\/linktr.ee\/maurofelippe","rel":"","context":"In &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/en\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/mmm.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/mmm.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/mmm.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1984,"url":"https:\/\/maurofelippe.com\/en\/mauro-felippe-no-blog-felipe-hart\/","url_meta":{"origin":2041,"position":4},"title":"Mauro felippe no blog felipe hart","author":"Mauro Felippe","date":"25\/08\/2023","format":false,"excerpt":"Na m\u00eddia, 2023: Meu novo livro CATARSE, pela Lura Editorial, na vis\u00e3o do Blog nacionalmente conhecido 'Felipe Hart', que desde j\u00e1 o agrade\u00e7o. Mat\u00e9ria completa clica aqui: http:\/\/felipehart.blogspot.com\/...\/a-volta-da-poesia... Obrigado! Contato com o autor e redes sociais: Facebook: https:\/\/www.facebook.com\/MauroFelippeAutor Instagram:\u00a0www.Instagram.com\/maurofelippe Youtube:\u00a0www.Youtube.com\/maurofelippe Linktree:\u00a0https:\/\/linktr.ee\/maurofelippe","rel":"","context":"In &quot;Mat\u00e9rias publicadas&quot;","block_context":{"text":"Mat\u00e9rias publicadas","link":"https:\/\/maurofelippe.com\/en\/category\/materias-publicadas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/asas.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/asas.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/asas.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/08\/asas.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2087,"url":"https:\/\/maurofelippe.com\/en\/entrevista-de-mauro-felippe-a-lc-o-caos-da-existencia-humana-em-forma-de-poesia\/","url_meta":{"origin":2041,"position":5},"title":"Entrevista de Mauro Felippe a LC:  O caos da exist\u00eancia humana em forma de poesia","author":"Mauro Felippe","date":"05\/10\/2023","format":false,"excerpt":"Marcadas por uma escrita intensa e por vezes fren\u00e9tica, as palavras de\u00a0Mauro Felippe\u00a0t\u00eam a capacidade de libertar e expressar o \u00e2mago do ser humano. Em\u00a0Catarse,\u00a0quinto livro publicado pelo catarinense, ele afugenta, por meio das palavras, as ang\u00fastias, inquieta\u00e7\u00f5es e dilemas da humanidade. Longe das poesias sobre relacionamentos e amor pr\u00f3prio,\u2026","rel":"","context":"In &quot;Imprensa&quot;","block_context":{"text":"Imprensa","link":"https:\/\/maurofelippe.com\/en\/category\/imprensa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/maurofelippe.com\/wp-content\/uploads\/2023\/10\/lc-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/posts\/2041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/comments?post=2041"}],"version-history":[{"count":2,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/posts\/2041\/revisions"}],"predecessor-version":[{"id":2045,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/posts\/2041\/revisions\/2045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/media\/2043"}],"wp:attachment":[{"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/media?parent=2041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/categories?post=2041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maurofelippe.com\/en\/wp-json\/wp\/v2\/tags?post=2041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}